{"id":1348,"date":"2024-02-06T15:38:41","date_gmt":"2024-02-06T15:38:41","guid":{"rendered":"https:\/\/mcservice.mo.it\/divisions\/"},"modified":"2024-07-24T16:59:20","modified_gmt":"2024-07-24T16:59:20","slug":"divisions","status":"publish","type":"page","link":"https:\/\/mcservice.mo.it\/en\/divisions\/","title":{"rendered":"Divisions"},"content":{"rendered":"[vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_color=&#8221;#111b27&#8243; bg_image=&#8221;50&#8243; bg_position=&#8221;center center&#8221; background_image_loading=&#8221;default&#8221; bg_repeat=&#8221;no-repeat&#8221; animated_gradient_bg=&#8221;true&#8221; animated_gradient_bg_color_1=&#8221;#3300ff&#8221; animated_gradient_bg_color_2=&#8221;#111b27&#8243; animated_gradient_bg_speed=&#8221;850&#8243; animated_gradient_bg_blending_mode=&#8221;linear&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;12%&#8221; constrain_group_1=&#8221;yes&#8221; bottom_padding=&#8221;12%&#8221; text_color=&#8221;light&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; color_overlay=&#8221;#111b27&#8243; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; parallax_bg=&#8221;true&#8221; parallax_bg_speed=&#8221;medium&#8221; shape_type=&#8221;&#8221; gradient_type=&#8221;default&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; left_padding_desktop=&#8221;4%&#8221; constrain_group_2=&#8221;yes&#8221; right_padding_desktop=&#8221;4%&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_column_text text_direction=&#8221;default&#8221;]\n<h3 style=\"text-align: center;\"><span style=\"color: #00ff99;\">DIVISIONS<\/span><\/h3>\n[\/vc_column_text][divider line_type=&#8221;No Line&#8221; custom_height=&#8221;40&#8243;][nectar_highlighted_text color_type=&#8221;regular&#8221; highlight_color=&#8221;#3300ff&#8221; text_color=&#8221;#ffffff&#8221; style=&#8221;regular_underline&#8221; highlight_expansion=&#8221;default&#8221; underline_thickness=&#8221;default&#8221; text_direction=&#8221;default&#8221; font_line_height=&#8221;1.5&#8243; custom_font_size=&#8221;6vh&#8221; font_size_phone=&#8221;4vh&#8221;]\n<h1 style=\"text-align: center;\">We offer innovative and customized solutions for the industry, from <a href=\"#presse\"><em>presses<\/em><\/a> to <a href=\"#presapezzo\"><em>piece gripping <\/em><\/a>technology, from <a href=\"#speciali\"><em>special machines<\/em><\/a> to <a href=\"#lean\"><em>production lines<\/em><\/a><\/h1>\n[\/nectar_highlighted_text][\/vc_column_inner][\/vc_row_inner][divider line_type=&#8221;No Line&#8221; custom_height=&#8221;0&#8243; custom_height_phone=&#8221;50&#8243;][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_color=&#8221;#ffffff&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;6%&#8221; bottom_padding=&#8221;6%&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; zindex=&#8221;100&#8243; overflow=&#8221;visible&#8221; id=&#8221;presse&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; shape_type=&#8221;&#8221; gradient_type=&#8221;default&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221; offset=&#8221;vc_hidden-sm vc_hidden-xs&#8221;][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; left_padding_desktop=&#8221;4%&#8221; constrain_group_2=&#8221;yes&#8221; right_padding_desktop=&#8221;4%&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; centered_text=&#8221;true&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][vc_column_text text_direction=&#8221;default&#8221;]\n<h3 style=\"text-align: center;\"><strong><span style=\"color: #111b27;\">Presses<\/span><\/strong><\/h3>\n[\/vc_column_text][divider line_type=&#8221;No Line&#8221; custom_height=&#8221;30&#8243;][vc_column_text text_direction=&#8221;default&#8221; max_width=&#8221;1000&#8243;]\n<p style=\"text-align: center;\">McService will study, by analyzing the customer&#8217;s production needs, the ideal pressing \/ assembly station to complete the operations in the fastest, safest and most precise way possible, with the possibility of customizing the workstation, for example, with material warehouses, operator interface and enslavement carriages.<\/p>\n[\/vc_column_text][divider line_type=&#8221;No Line&#8221; custom_height=&#8221;70&#8243;][\/vc_column_inner][\/vc_row_inner][tabbed_section style=&#8221;vertical_modern&#8221; tab_color=&#8221;Extra-Color-2&#8243; vs_content_animation=&#8221;fade&#8221; vs_link_animation=&#8221;opacity&#8221; vs_navigation_alignment=&#8221;left&#8221; vs_navigation_width_2=&#8221;25%&#8221; vs_navigation_func=&#8221;default&#8221; vs_navigation_width=&#8221;regular&#8221; vs_navigation_spacing=&#8221;15px&#8221; vs_navigation_mobile_display=&#8221;visible&#8221; vs_tab_spacing=&#8221;5%&#8221;][tab icon_family=&#8221;iconsmind&#8221; title=&#8221;Rotor installation&#8221; id=&#8221;1716821559047-0&#8243; tab_id=&#8221;1716821559050-3&#8243;][vc_row_inner column_margin=&#8221;40px&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;padding-3-percent&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;no-extra-padding&#8221; column_padding_position=&#8221;right&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;7\/12&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][vc_column_text text_direction=&#8221;default&#8221;]We create vertical presses with a rotary table for the multiple fitting of rotors, thus guaranteeing efficiency and safety even in unattended processes.[\/vc_column_text][vc_column_text text_direction=&#8221;default&#8221;]\n<h6><strong><span style=\"color: #111b27;\">Adaptability and Customized Programming<\/span><\/strong><\/h6>\n<p> The press can be configured to work with different sized rotors, thanks to the interchangeable tools provided. Programming via PLC and industrial PC allows personalized and precise work cycles.[\/vc_column_text][divider line_type=&#8221;Full Width Line&#8221; line_thickness=&#8221;1&#8243; divider_color=&#8221;extra-color-3&#8243; custom_height=&#8221;30&#8243;][vc_column_text text_direction=&#8221;default&#8221;]\n<h6><strong><span style=\"color: #111b27;\">Advanced Security and Control<\/span><\/strong><\/h6>\n<p> Safety systems, such as infrared radar and barriers, ensure a safe working environment. The work area is separated and the hydraulic power unit is protected to reduce noise.[\/vc_column_text][divider line_type=&#8221;No Line&#8221; custom_height=&#8221;30&#8243;][nectar_cta btn_style=&#8221;text-reveal-wave&#8221; heading_tag=&#8221;h1&#8243; button_color=&#8221;accent-color&#8221; button_color_hover=&#8221;#00ff99&#8243; text_color=&#8221;#111b27&#8243; text_color_hover=&#8221;#111b27&#8243; button_border_thickness=&#8221;0px&#8221; link_type=&#8221;new_tab&#8221; alignment=&#8221;center&#8221; alignment_tablet=&#8221;left&#8221; alignment_phone=&#8221;left&#8221; constrain_group_1=&#8221;yes&#8221; constrain_group_3=&#8221;yes&#8221; constrain_group_4=&#8221;yes&#8221; display=&#8221;inline&#8221; display_tablet=&#8221;inherit&#8221; display_phone=&#8221;inherit&#8221; icon_family=&#8221;none&#8221; link_text=&#8221;Contact us&#8221; padding_top=&#8221;19&#8243; padding_bottom=&#8221;19&#8243; padding_left=&#8221;32&#8243; padding_right=&#8221;32&#8243; url=&#8221;https:\/\/mcservice.mo.it\/contatti\/&#8221; font_size_desktop=&#8221;18px&#8221; margin_top=&#8221;30&#8243; margin_bottom=&#8221;30&#8243; margin_left=&#8221;0&#8243; margin_right=&#8221;10px&#8221;][nectar_cta btn_style=&#8221;basic&#8221; heading_tag=&#8221;h1&#8243; button_color=&#8221;default&#8221; button_color_hover=&#8221;#3300ff&#8221; text_color=&#8221;#3300ff&#8221; text_color_hover=&#8221;#ffffff&#8221; button_border_color=&#8221;#3300ff&#8221; button_border_color_hover=&#8221;#3300ff&#8221; button_border_thickness=&#8221;2px&#8221; link_type=&#8221;new_tab&#8221; alignment=&#8221;center&#8221; alignment_tablet=&#8221;left&#8221; alignment_phone=&#8221;left&#8221; constrain_group_1=&#8221;yes&#8221; constrain_group_3=&#8221;yes&#8221; constrain_group_4=&#8221;yes&#8221; display=&#8221;inline&#8221; display_tablet=&#8221;inherit&#8221; display_phone=&#8221;inherit&#8221; icon_family=&#8221;none&#8221; link_text=&#8221;Documentation&#8221; padding_top=&#8221;12&#8243; padding_bottom=&#8221;12&#8243; padding_left=&#8221;32&#8243; padding_right=&#8221;32&#8243; url=&#8221;https:\/\/mcservice.mo.it\/wp-content\/uploads\/2024\/05\/Documentazione-pressa-piantaggio-rotori_con-ingombri-generali-MEC-56-400.pdf&#8221; font_size_desktop=&#8221;18px&#8221; margin_top=&#8221;30&#8243; margin_bottom=&#8221;30&#8243;][\/vc_column_inner][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;5\/12&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][image_with_animation image_url=&#8221;625&#8243; image_size=&#8221;full&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;Grow In&#8221; animation_easing=&#8221;default&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;zoom-crop&#8221; alignment=&#8221;center&#8221; border_radius=&#8221;5px&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; max_width=&#8221;110%&#8221; max_width_mobile=&#8221;default&#8221;][\/vc_column_inner][\/vc_row_inner][\/tab][tab icon_family=&#8221;iconsmind&#8221; title=&#8221;Oil seal installation&#8221; id=&#8221;1716821559352-4&#8243; tab_id=&#8221;1716821559354-9&#8243;][vc_row_inner column_margin=&#8221;40px&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;7\/12&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_column_text css=&#8221;.vc_custom_1709116450391{padding-right: 10% !important;}&#8221; text_direction=&#8221;default&#8221;]Precision pneumatic presses with dedicated tools for driving oil seals, edging, crimping, assembly, keying, bending, shearing or any other application requiring permitted loads.<br \/>The presses are equipped with a precision slider that guides the cylinder rod to which the customized presser is connected depending on the type of pressing or operation to be performed. The slider, thanks to its four pre-loaded pads that slide in pairs on two rails, guarantees precise installation.[\/vc_column_text][divider line_type=&#8221;No Line&#8221; custom_height=&#8221;30&#8243;][nectar_cta btn_style=&#8221;text-reveal-wave&#8221; heading_tag=&#8221;h1&#8243; button_color=&#8221;accent-color&#8221; button_color_hover=&#8221;#00ff99&#8243; text_color=&#8221;#111b27&#8243; text_color_hover=&#8221;#111b27&#8243; button_border_thickness=&#8221;0px&#8221; link_type=&#8221;new_tab&#8221; alignment=&#8221;center&#8221; alignment_tablet=&#8221;default&#8221; alignment_phone=&#8221;default&#8221; constrain_group_3=&#8221;yes&#8221; constrain_group_4=&#8221;yes&#8221; display=&#8221;inline&#8221; display_tablet=&#8221;inherit&#8221; display_phone=&#8221;inherit&#8221; icon_family=&#8221;none&#8221; link_text=&#8221;Contact us&#8221; padding_top=&#8221;19&#8243; padding_bottom=&#8221;19&#8243; padding_left=&#8221;32&#8243; padding_right=&#8221;32&#8243; url=&#8221;https:\/\/mcservice.mo.it\/contatti\/&#8221; font_size_desktop=&#8221;18px&#8221; margin_top=&#8221;7px&#8221; margin_bottom=&#8221;7px&#8221; margin_left=&#8221;0&#8243; margin_right=&#8221;10px&#8221;][nectar_cta btn_style=&#8221;basic&#8221; heading_tag=&#8221;h1&#8243; button_color=&#8221;default&#8221; button_color_hover=&#8221;#3300ff&#8221; text_color=&#8221;#3300ff&#8221; text_color_hover=&#8221;#ffffff&#8221; button_border_color=&#8221;#3300ff&#8221; button_border_color_hover=&#8221;#3300ff&#8221; button_border_thickness=&#8221;2px&#8221; link_type=&#8221;new_tab&#8221; alignment=&#8221;center&#8221; alignment_tablet=&#8221;default&#8221; alignment_phone=&#8221;default&#8221; constrain_group_1=&#8221;yes&#8221; constrain_group_3=&#8221;yes&#8221; constrain_group_4=&#8221;yes&#8221; display=&#8221;inline&#8221; display_tablet=&#8221;inherit&#8221; display_phone=&#8221;inherit&#8221; icon_family=&#8221;none&#8221; link_text=&#8221;Documentation&#8221; padding_top=&#8221;12&#8243; padding_bottom=&#8221;12&#8243; padding_left=&#8221;32&#8243; padding_right=&#8221;32&#8243; url=&#8221;https:\/\/mcservice.mo.it\/wp-content\/uploads\/2024\/05\/Documentazione-pressa-piantaggio-paraoli.pdf&#8221; font_size_desktop=&#8221;18px&#8221; margin_top=&#8221;7px&#8221; margin_bottom=&#8221;7px&#8221;][\/vc_column_inner][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;5\/12&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][image_with_animation image_url=&#8221;511&#8243; image_size=&#8221;full&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;Grow In&#8221; animation_easing=&#8221;default&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;zoom-crop&#8221; alignment=&#8221;center&#8221; border_radius=&#8221;5px&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; max_width=&#8221;110%&#8221; max_width_mobile=&#8221;default&#8221;][\/vc_column_inner][\/vc_row_inner][\/tab][tab icon_family=&#8221;iconsmind&#8221; title=&#8221;Spinner installation&#8221; id=&#8221;1716821559594-6&#8243; tab_id=&#8221;1716821559595-2&#8243;][vc_row_inner column_margin=&#8221;40px&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;padding-3-percent&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;right&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;7\/12&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][vc_column_text css=&#8221;.vc_custom_1709202363982{padding-right: 10% !important;}&#8221; text_direction=&#8221;default&#8221;]Double inserter station for the partial assembly of electric motors. This particular station involves the installation of spinners, bearings and oil seals and the insertion of Seeger rings.[\/vc_column_text][vc_column_text text_direction=&#8221;default&#8221;]\n<h6><strong><span style=\"color: #111b27;\">Process objectification and documentation<\/span><\/strong><\/h6>\n<p> We offer the possibility of integrating a user interface for precise control over each work cycle.[\/vc_column_text][divider line_type=&#8221;Full Width Line&#8221; line_thickness=&#8221;1&#8243; divider_color=&#8221;extra-color-3&#8243; custom_height=&#8221;30&#8243;][vc_column_text text_direction=&#8221;default&#8221;]\n<h6><strong><span style=\"color: #111b27;\">Flexibility and Efficiency<\/span><\/strong><\/h6>\n<p> With quick connections for pressers and dedicated equipment, our presses allow different pressing operations[\/vc_column_text][divider line_type=&#8221;No Line&#8221; custom_height=&#8221;30&#8243;][nectar_cta btn_style=&#8221;text-reveal-wave&#8221; heading_tag=&#8221;h1&#8243; button_color=&#8221;accent-color&#8221; button_color_hover=&#8221;#00ff99&#8243; text_color=&#8221;#111b27&#8243; text_color_hover=&#8221;#111b27&#8243; button_border_thickness=&#8221;0px&#8221; link_type=&#8221;new_tab&#8221; alignment=&#8221;center&#8221; alignment_tablet=&#8221;default&#8221; alignment_phone=&#8221;default&#8221; constrain_group_3=&#8221;yes&#8221; constrain_group_4=&#8221;yes&#8221; display=&#8221;inline&#8221; display_tablet=&#8221;inherit&#8221; display_phone=&#8221;inherit&#8221; icon_family=&#8221;none&#8221; link_text=&#8221;Contact us&#8221; padding_top=&#8221;19&#8243; padding_bottom=&#8221;19&#8243; padding_left=&#8221;32&#8243; padding_right=&#8221;32&#8243; url=&#8221;https:\/\/mcservice.mo.it\/contatti\/&#8221; font_size_desktop=&#8221;18px&#8221; margin_top=&#8221;7px&#8221; margin_bottom=&#8221;7px&#8221; margin_left=&#8221;0&#8243; margin_right=&#8221;10px&#8221;][nectar_cta btn_style=&#8221;basic&#8221; heading_tag=&#8221;h1&#8243; button_color=&#8221;default&#8221; button_color_hover=&#8221;#3300ff&#8221; text_color=&#8221;#3300ff&#8221; text_color_hover=&#8221;#ffffff&#8221; button_border_color=&#8221;#3300ff&#8221; button_border_color_hover=&#8221;#3300ff&#8221; button_border_thickness=&#8221;2px&#8221; link_type=&#8221;new_tab&#8221; alignment=&#8221;center&#8221; alignment_tablet=&#8221;default&#8221; alignment_phone=&#8221;default&#8221; constrain_group_1=&#8221;yes&#8221; constrain_group_3=&#8221;yes&#8221; constrain_group_4=&#8221;yes&#8221; display=&#8221;inline&#8221; display_tablet=&#8221;inherit&#8221; display_phone=&#8221;inherit&#8221; icon_family=&#8221;none&#8221; link_text=&#8221;Documentation&#8221; padding_top=&#8221;12&#8243; padding_bottom=&#8221;12&#8243; padding_left=&#8221;32&#8243; padding_right=&#8221;32&#8243; url=&#8221;https:\/\/mcservice.mo.it\/wp-content\/uploads\/2024\/05\/Documentazione-pressa-seegerpdf.pdf&#8221; font_size_desktop=&#8221;18px&#8221; margin_top=&#8221;7px&#8221; margin_bottom=&#8221;7px&#8221;][\/vc_column_inner][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;5\/12&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][image_with_animation image_url=&#8221;564&#8243; image_size=&#8221;full&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;Grow In&#8221; animation_easing=&#8221;default&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;zoom-crop&#8221; alignment=&#8221;center&#8221; border_radius=&#8221;5px&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; max_width=&#8221;110%&#8221; max_width_mobile=&#8221;default&#8221;][\/vc_column_inner][\/vc_row_inner][\/tab][tab icon_family=&#8221;iconsmind&#8221; title=&#8221;Bearing installation&#8221; id=&#8221;1716821559858-6&#8243; tab_id=&#8221;1716821559860-5&#8243;][vc_row_inner column_margin=&#8221;40px&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;7\/12&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_column_text css=&#8221;.vc_custom_1710767132353{padding-right: 10% !important;}&#8221; text_direction=&#8221;default&#8221;]Vertical and horizontal presses for bearing installation, with hydraulic or electric movement, supplied with a number of interchangeable fitting tools, which allow you to work with various sizes of rotors and bearings. The presses can be controlled in manual or automatic mode.[\/vc_column_text][vc_column_text text_direction=&#8221;default&#8221;]\n<h6><strong><span style=\"color: #111b27;\">Vertical presses <\/span><\/strong><\/h6>\n<p> They provide for the control of the installation quota. The height of the lower table is adjustable by PLC according to the program, to meet the biometric needs of the operator and depending on the dimensions of the items to be processed. The height of the upper presser is adjusted accordingly, by program, so as to leave adequate loading space, thus reducing the approach stroke to a minimum.<br \/>\n[\/vc_column_text][divider line_type=&#8221;Full Width Line&#8221; line_thickness=&#8221;1&#8243; divider_color=&#8221;extra-color-3&#8243; custom_height=&#8221;30&#8243;][vc_column_text text_direction=&#8221;default&#8221;]\n<h6><strong><span style=\"color: #111b27;\">Horizontal presses<\/span><\/strong><\/h6>\n<p> An alternative solution to vertical presses is our horizontal press for installing bearings on rotors and shafts. In this machine, the rotor can be placed horizontally in a special cradle, which will hold it in position, for driving the bearings. The tools are supplied with the machine and interchangeable to overcome different sizes.<br \/>\n[\/vc_column_text][divider line_type=&#8221;No Line&#8221; custom_height=&#8221;30&#8243;][nectar_cta btn_style=&#8221;text-reveal-wave&#8221; heading_tag=&#8221;h1&#8243; button_color=&#8221;accent-color&#8221; button_color_hover=&#8221;#00ff99&#8243; text_color=&#8221;#111b27&#8243; text_color_hover=&#8221;#111b27&#8243; button_border_thickness=&#8221;0px&#8221; link_type=&#8221;new_tab&#8221; alignment=&#8221;center&#8221; alignment_tablet=&#8221;default&#8221; alignment_phone=&#8221;default&#8221; constrain_group_3=&#8221;yes&#8221; constrain_group_4=&#8221;yes&#8221; display=&#8221;inline&#8221; display_tablet=&#8221;inherit&#8221; display_phone=&#8221;inherit&#8221; icon_family=&#8221;none&#8221; link_text=&#8221;Contact us&#8221; padding_top=&#8221;19&#8243; padding_bottom=&#8221;19&#8243; padding_left=&#8221;32&#8243; padding_right=&#8221;32&#8243; url=&#8221;https:\/\/mcservice.mo.it\/contatti\/&#8221; font_size_desktop=&#8221;18px&#8221; margin_top=&#8221;7px&#8221; margin_bottom=&#8221;7px&#8221; margin_left=&#8221;0&#8243; margin_right=&#8221;10px&#8221;][nectar_cta btn_style=&#8221;basic&#8221; heading_tag=&#8221;h1&#8243; button_color=&#8221;default&#8221; button_color_hover=&#8221;#3300ff&#8221; text_color=&#8221;#3300ff&#8221; text_color_hover=&#8221;#ffffff&#8221; button_border_color=&#8221;#3300ff&#8221; button_border_color_hover=&#8221;#3300ff&#8221; button_border_thickness=&#8221;2px&#8221; link_type=&#8221;new_tab&#8221; alignment=&#8221;center&#8221; alignment_tablet=&#8221;default&#8221; alignment_phone=&#8221;default&#8221; constrain_group_1=&#8221;yes&#8221; constrain_group_3=&#8221;yes&#8221; constrain_group_4=&#8221;yes&#8221; display=&#8221;inline&#8221; display_tablet=&#8221;inherit&#8221; display_phone=&#8221;inherit&#8221; icon_family=&#8221;none&#8221; link_text=&#8221;Documentation&#8221; padding_top=&#8221;12&#8243; padding_bottom=&#8221;12&#8243; padding_left=&#8221;32&#8243; padding_right=&#8221;32&#8243; url=&#8221;https:\/\/mcservice.mo.it\/wp-content\/uploads\/2024\/05\/Documentazione-pressa-orizzontale.pdf&#8221; font_size_desktop=&#8221;18px&#8221; margin_top=&#8221;7px&#8221; margin_bottom=&#8221;7px&#8221;][\/vc_column_inner][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;5\/12&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][image_with_animation image_url=&#8221;565&#8243; image_size=&#8221;full&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;Grow In&#8221; animation_easing=&#8221;default&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;zoom-crop&#8221; alignment=&#8221;center&#8221; border_radius=&#8221;5px&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; max_width=&#8221;110%&#8221; max_width_mobile=&#8221;default&#8221;][\/vc_column_inner][\/vc_row_inner][\/tab][tab icon_family=&#8221;iconsmind&#8221; title=&#8221;Fan installation&#8221; id=&#8221;1716821560148-5&#8243; tab_id=&#8221;1716821560149-1&#8243;][vc_row_inner column_margin=&#8221;40px&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;7\/12&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_column_text css=&#8221;.vc_custom_1710430227524{padding-right: 10% !important;}&#8221; text_direction=&#8221;default&#8221;]Multifunction insertion station for installing fans, bearings, oil seals and shields.<br \/>\n[\/vc_column_text][divider line_type=&#8221;No Line&#8221; custom_height=&#8221;30&#8243;][vc_column_text text_direction=&#8221;default&#8221;]\n<h6><strong><span style=\"color: #111b27;\">Multifunction <\/span><\/strong><\/h6>\n<p> The station can work on a self-learning function or based on pre-entered data. The interchangeability of the equipment allows the fitting of bearings, oil seals and fans. The axes of the installation zones are independent. The machine is equipped with a touchscreen monitor through which it is possible to enter the work program to be carried out or modify the operating parameters. For greater ergonomics, the height of the work area is adjustable.<br \/>\n[\/vc_column_text][nectar_cta btn_style=&#8221;text-reveal-wave&#8221; heading_tag=&#8221;h1&#8243; button_color=&#8221;accent-color&#8221; button_color_hover=&#8221;#00ff99&#8243; text_color=&#8221;#111b27&#8243; text_color_hover=&#8221;#111b27&#8243; button_border_thickness=&#8221;0px&#8221; link_type=&#8221;new_tab&#8221; alignment=&#8221;center&#8221; alignment_tablet=&#8221;default&#8221; alignment_phone=&#8221;default&#8221; constrain_group_3=&#8221;yes&#8221; constrain_group_4=&#8221;yes&#8221; display=&#8221;inline&#8221; display_tablet=&#8221;inherit&#8221; display_phone=&#8221;inherit&#8221; icon_family=&#8221;none&#8221; link_text=&#8221;Contact us&#8221; padding_top=&#8221;19&#8243; padding_bottom=&#8221;19&#8243; padding_left=&#8221;32&#8243; padding_right=&#8221;32&#8243; url=&#8221;https:\/\/mcservice.mo.it\/contatti\/&#8221; font_size_desktop=&#8221;18px&#8221; margin_top=&#8221;7px&#8221; margin_bottom=&#8221;7px&#8221; margin_left=&#8221;0&#8243; margin_right=&#8221;10px&#8221;][nectar_cta btn_style=&#8221;basic&#8221; heading_tag=&#8221;h1&#8243; button_color=&#8221;default&#8221; button_color_hover=&#8221;#3300ff&#8221; text_color=&#8221;#3300ff&#8221; text_color_hover=&#8221;#ffffff&#8221; button_border_color=&#8221;#3300ff&#8221; button_border_color_hover=&#8221;#3300ff&#8221; button_border_thickness=&#8221;2px&#8221; link_type=&#8221;new_tab&#8221; alignment=&#8221;center&#8221; alignment_tablet=&#8221;default&#8221; alignment_phone=&#8221;default&#8221; constrain_group_1=&#8221;yes&#8221; constrain_group_3=&#8221;yes&#8221; constrain_group_4=&#8221;yes&#8221; display=&#8221;inline&#8221; display_tablet=&#8221;inherit&#8221; display_phone=&#8221;inherit&#8221; icon_family=&#8221;none&#8221; link_text=&#8221;Documentation&#8221; padding_top=&#8221;12&#8243; padding_bottom=&#8221;12&#8243; padding_left=&#8221;32&#8243; padding_right=&#8221;32&#8243; url=&#8221;https:\/\/mcservice.mo.it\/wp-content\/uploads\/2024\/05\/Documentazione-pressa-piantaggio-ventole.pdf&#8221; font_size_desktop=&#8221;18px&#8221; margin_top=&#8221;7px&#8221; margin_bottom=&#8221;7px&#8221;][\/vc_column_inner][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;5\/12&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][image_with_animation image_url=&#8221;499&#8243; image_size=&#8221;full&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;Grow In&#8221; animation_easing=&#8221;default&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;zoom-crop&#8221; alignment=&#8221;center&#8221; border_radius=&#8221;5px&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; max_width=&#8221;110%&#8221; max_width_mobile=&#8221;default&#8221;][\/vc_column_inner][\/vc_row_inner][\/tab][\/tabbed_section][nectar_highlighted_text color_type=&#8221;regular&#8221; highlight_color=&#8221;#3300ff&#8221; text_color=&#8221;#111b27&#8243; style=&#8221;regular_underline&#8221; highlight_expansion=&#8221;default&#8221; underline_thickness=&#8221;2px&#8221; text_direction=&#8221;default&#8221;]\n<h5 style=\"text-align: center;\">We offer innovative and customized solutions for the industry, from <strong>presses<\/strong> to <em><a href=\"#presapezzo\">piece gripping<\/a><\/em> technology, from <a href=\"#speciali\"><em>special machines<\/em><\/a> to <a href=\"#lean\"><em>production lines<\/em><\/a><\/h5>\n[\/nectar_highlighted_text][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221; offset=&#8221;vc_hidden-lg vc_hidden-md&#8221;][divider line_type=&#8221;No Line&#8221; custom_height=&#8221;0&#8243; custom_height_phone=&#8221;50&#8243;][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; left_padding_desktop=&#8221;4%&#8221; constrain_group_2=&#8221;yes&#8221; right_padding_desktop=&#8221;4%&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; centered_text=&#8221;true&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][vc_column_text text_direction=&#8221;default&#8221;]\n<h3 style=\"text-align: center;\"><strong><span style=\"color: #111b27;\">Presses<\/span><\/strong><\/h3>\n[\/vc_column_text][divider line_type=&#8221;No Line&#8221; custom_height=&#8221;30&#8243;][vc_column_text text_direction=&#8221;default&#8221; max_width=&#8221;1000&#8243;]\n<p style=\"text-align: center;\">McService will study, by analyzing the customer&#8217;s production needs, the ideal pressing \/ assembly station to complete the operations in the fastest, safest and most precise way possible, with the possibility of customizing the workstation, for example, with material warehouses, operator interface and enslavement carriages.<\/p>\n[\/vc_column_text][divider line_type=&#8221;No Line&#8221; custom_height=&#8221;70&#8243;][\/vc_column_inner][\/vc_row_inner][tabbed_section style=&#8221;vertical_scrolling&#8221; tab_color=&#8221;Extra-Color-2&#8243; vs_navigation_func=&#8221;default&#8221; vs_navigation_width=&#8221;regular&#8221; vs_navigation_spacing=&#8221;15px&#8221; vs_navigation_mobile_display=&#8221;visible&#8221; vs_tab_spacing=&#8221;10%&#8221; vs_tab_tag=&#8221;p&#8221; vs_cta_style=&#8221;see-through&#8221; vs_cta_bg_color=&#8221;default&#8221; vs_cta_heading_tag=&#8221;h6&#8243; vs_sticky_aspect=&#8221;default&#8221;][tab icon_family=&#8221;iconsmind&#8221; title=&#8221;<br \/>\n&lt;h3&gt;Rotor installation&lt;\/h3&gt;<br \/>\n&#8221; id=&#8221;1716821560631-2&#8243; tab_id=&#8221;1716821560633-3&#8243;][vc_row_inner column_margin=&#8221;40px&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;column_reverse&#8221; column_direction_phone=&#8221;column_reverse&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;padding-3-percent&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;no-extra-padding&#8221; column_padding_position=&#8221;right&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;7\/12&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][vc_column_text text_direction=&#8221;default&#8221;]We create vertical presses with a rotary table for the multiple fitting of rotors, thus guaranteeing efficiency and safety even in unattended processes.[\/vc_column_text][vc_column_text text_direction=&#8221;default&#8221;]\n<h6><strong><span style=\"color: #111b27;\">Adaptability and Customized Programming<\/span><\/strong><\/h6>\n<p> The press can be configured to work with different sized rotors, thanks to the interchangeable tools provided. Programming via PLC and industrial PC allows personalized and precise work cycles.[\/vc_column_text][divider line_type=&#8221;Full Width Line&#8221; line_thickness=&#8221;1&#8243; divider_color=&#8221;extra-color-3&#8243; custom_height=&#8221;30&#8243;][vc_column_text text_direction=&#8221;default&#8221;]\n<h6><strong><span style=\"color: #111b27;\">Advanced Security and Control<\/span><\/strong><\/h6>\n<p> Safety systems, such as infrared radar and barriers, ensure a safe working environment. The work area is separated and the hydraulic power unit is protected to reduce noise.[\/vc_column_text][divider line_type=&#8221;No Line&#8221; custom_height=&#8221;30&#8243;][nectar_cta btn_style=&#8221;text-reveal-wave&#8221; heading_tag=&#8221;h1&#8243; button_color=&#8221;accent-color&#8221; button_color_hover=&#8221;#00ff99&#8243; text_color=&#8221;#111b27&#8243; text_color_hover=&#8221;#111b27&#8243; button_border_thickness=&#8221;0px&#8221; link_type=&#8221;new_tab&#8221; alignment=&#8221;left&#8221; alignment_tablet=&#8221;default&#8221; alignment_phone=&#8221;default&#8221; constrain_group_1=&#8221;yes&#8221; constrain_group_3=&#8221;yes&#8221; constrain_group_4=&#8221;yes&#8221; display=&#8221;block&#8221; display_tablet=&#8221;inherit&#8221; display_phone=&#8221;inherit&#8221; icon_family=&#8221;none&#8221; link_text=&#8221;Contact us&#8221; padding_top=&#8221;19&#8243; padding_bottom=&#8221;19&#8243; padding_left=&#8221;32&#8243; padding_right=&#8221;32&#8243; url=&#8221;https:\/\/mcservice.mo.it\/contatti\/&#8221; font_size_desktop=&#8221;18px&#8221; margin_top=&#8221;30&#8243; margin_bottom=&#8221;30&#8243;][nectar_cta btn_style=&#8221;basic&#8221; heading_tag=&#8221;h1&#8243; button_color=&#8221;default&#8221; button_color_hover=&#8221;#3300ff&#8221; text_color=&#8221;#3300ff&#8221; text_color_hover=&#8221;#ffffff&#8221; button_border_color=&#8221;#3300ff&#8221; button_border_color_hover=&#8221;#3300ff&#8221; button_border_thickness=&#8221;2px&#8221; link_type=&#8221;new_tab&#8221; alignment=&#8221;left&#8221; alignment_tablet=&#8221;default&#8221; alignment_phone=&#8221;default&#8221; constrain_group_1=&#8221;yes&#8221; constrain_group_3=&#8221;yes&#8221; constrain_group_4=&#8221;yes&#8221; display=&#8221;block&#8221; display_tablet=&#8221;inherit&#8221; display_phone=&#8221;inherit&#8221; icon_family=&#8221;none&#8221; link_text=&#8221;Documentation&#8221; padding_top=&#8221;12&#8243; padding_bottom=&#8221;12&#8243; padding_left=&#8221;32&#8243; padding_right=&#8221;32&#8243; url=&#8221;https:\/\/mcservice.mo.it\/wp-content\/uploads\/2024\/05\/Documentazione-pressa-piantaggio-rotori_con-ingombri-generali-MEC-56-400.pdf&#8221; font_size_desktop=&#8221;18px&#8221; margin_top=&#8221;30&#8243; margin_bottom=&#8221;30&#8243;][\/vc_column_inner][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;5\/12&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][image_with_animation image_url=&#8221;625&#8243; image_size=&#8221;full&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;Grow In&#8221; animation_easing=&#8221;default&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;zoom-crop&#8221; alignment=&#8221;center&#8221; border_radius=&#8221;5px&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; max_width=&#8221;110%&#8221; max_width_mobile=&#8221;default&#8221;][\/vc_column_inner][\/vc_row_inner][\/tab][tab icon_family=&#8221;iconsmind&#8221; title=&#8221;<br \/>\n&lt;h3&gt;Oil seal installation&lt;\/h3&gt;<br \/>\n&#8221; id=&#8221;1716821560926-4&#8243; tab_id=&#8221;1716821560927-10&#8243;][vc_row_inner column_margin=&#8221;40px&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;column_reverse&#8221; column_direction_phone=&#8221;column_reverse&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;7\/12&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_column_text css=&#8221;.vc_custom_1709116450391{padding-right: 10% !important;}&#8221; text_direction=&#8221;default&#8221;]Precision pneumatic presses with dedicated tools for driving oil seals, edging, crimping, assembly, keying, bending, shearing or any other application requiring permitted loads.<br \/>The presses are equipped with a precision slider that guides the cylinder rod to which the customized presser is connected depending on the type of pressing or operation to be performed. The slider, thanks to its four pre-loaded pads that slide in pairs on two rails, guarantees precise installation.[\/vc_column_text][divider line_type=&#8221;No Line&#8221; custom_height=&#8221;30&#8243;][nectar_cta btn_style=&#8221;text-reveal-wave&#8221; heading_tag=&#8221;h1&#8243; button_color=&#8221;accent-color&#8221; button_color_hover=&#8221;#00ff99&#8243; text_color=&#8221;#111b27&#8243; text_color_hover=&#8221;#111b27&#8243; button_border_thickness=&#8221;0px&#8221; link_type=&#8221;new_tab&#8221; alignment=&#8221;left&#8221; alignment_tablet=&#8221;default&#8221; alignment_phone=&#8221;default&#8221; constrain_group_1=&#8221;yes&#8221; constrain_group_3=&#8221;yes&#8221; constrain_group_4=&#8221;yes&#8221; display=&#8221;block&#8221; display_tablet=&#8221;inherit&#8221; display_phone=&#8221;inherit&#8221; icon_family=&#8221;none&#8221; link_text=&#8221;Contact us&#8221; padding_top=&#8221;19&#8243; padding_bottom=&#8221;19&#8243; padding_left=&#8221;32&#8243; padding_right=&#8221;32&#8243; url=&#8221;https:\/\/mcservice.mo.it\/contatti\/&#8221; font_size_desktop=&#8221;18px&#8221; margin_top=&#8221;30&#8243; margin_bottom=&#8221;30&#8243;][nectar_cta btn_style=&#8221;basic&#8221; heading_tag=&#8221;h1&#8243; button_color=&#8221;default&#8221; button_color_hover=&#8221;#3300ff&#8221; text_color=&#8221;#3300ff&#8221; text_color_hover=&#8221;#ffffff&#8221; button_border_color=&#8221;#3300ff&#8221; button_border_color_hover=&#8221;#3300ff&#8221; button_border_thickness=&#8221;2px&#8221; link_type=&#8221;new_tab&#8221; alignment=&#8221;left&#8221; alignment_tablet=&#8221;default&#8221; alignment_phone=&#8221;default&#8221; constrain_group_1=&#8221;yes&#8221; constrain_group_3=&#8221;yes&#8221; constrain_group_4=&#8221;yes&#8221; display=&#8221;block&#8221; display_tablet=&#8221;inherit&#8221; display_phone=&#8221;inherit&#8221; icon_family=&#8221;none&#8221; link_text=&#8221;Documentation&#8221; padding_top=&#8221;12&#8243; padding_bottom=&#8221;12&#8243; padding_left=&#8221;32&#8243; padding_right=&#8221;32&#8243; url=&#8221;https:\/\/mcservice.mo.it\/wp-content\/uploads\/2024\/05\/Documentazione-pressa-piantaggio-paraoli.pdf&#8221; font_size_desktop=&#8221;18px&#8221; margin_top=&#8221;7px&#8221; margin_bottom=&#8221;7px&#8221;][\/vc_column_inner][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;5\/12&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][image_with_animation image_url=&#8221;511&#8243; image_size=&#8221;full&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;Grow In&#8221; animation_easing=&#8221;default&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;zoom-crop&#8221; alignment=&#8221;center&#8221; border_radius=&#8221;5px&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; max_width=&#8221;110%&#8221; max_width_mobile=&#8221;default&#8221;][\/vc_column_inner][\/vc_row_inner][\/tab][tab icon_family=&#8221;iconsmind&#8221; title=&#8221;<br \/>\n&lt;h3&gt;Spinner installation&lt;\/h3&gt;<br \/>\n&#8221; id=&#8221;1716821561147-5&#8243; tab_id=&#8221;1716821561148-4&#8243;][vc_row_inner column_margin=&#8221;40px&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;column_reverse&#8221; column_direction_phone=&#8221;column_reverse&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;padding-3-percent&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;right&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;7\/12&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][vc_column_text css=&#8221;.vc_custom_1709202363982{padding-right: 10% !important;}&#8221; text_direction=&#8221;default&#8221;]Double inserter station for the partial assembly of electric motors. This particular station involves the installation of spinners, bearings and oil seals and the insertion of Seeger rings.[\/vc_column_text][vc_column_text text_direction=&#8221;default&#8221;]\n<h6><strong><span style=\"color: #111b27;\">Process objectification and documentation<\/span><\/strong><\/h6>\n<p> We offer the possibility of integrating a user interface for precise control over each work cycle.[\/vc_column_text][divider line_type=&#8221;Full Width Line&#8221; line_thickness=&#8221;1&#8243; divider_color=&#8221;extra-color-3&#8243; custom_height=&#8221;30&#8243;][vc_column_text text_direction=&#8221;default&#8221;]\n<h6><strong><span style=\"color: #111b27;\">Flexibility and Efficiency<\/span><\/strong><\/h6>\n<p> With quick connections for pressers and dedicated equipment, our presses allow different pressing operations[\/vc_column_text][divider line_type=&#8221;No Line&#8221; custom_height=&#8221;30&#8243;][nectar_cta btn_style=&#8221;text-reveal-wave&#8221; heading_tag=&#8221;h1&#8243; button_color=&#8221;accent-color&#8221; button_color_hover=&#8221;#00ff99&#8243; text_color=&#8221;#111b27&#8243; text_color_hover=&#8221;#111b27&#8243; button_border_thickness=&#8221;0px&#8221; link_type=&#8221;new_tab&#8221; alignment=&#8221;left&#8221; alignment_tablet=&#8221;default&#8221; alignment_phone=&#8221;default&#8221; constrain_group_1=&#8221;yes&#8221; constrain_group_3=&#8221;yes&#8221; constrain_group_4=&#8221;yes&#8221; display=&#8221;block&#8221; display_tablet=&#8221;inherit&#8221; display_phone=&#8221;inherit&#8221; icon_family=&#8221;none&#8221; link_text=&#8221;Contact us&#8221; padding_top=&#8221;19&#8243; padding_bottom=&#8221;19&#8243; padding_left=&#8221;32&#8243; padding_right=&#8221;32&#8243; url=&#8221;https:\/\/mcservice.mo.it\/contatti\/&#8221; font_size_desktop=&#8221;18px&#8221; margin_top=&#8221;30&#8243; margin_bottom=&#8221;30&#8243;][nectar_cta btn_style=&#8221;basic&#8221; heading_tag=&#8221;h1&#8243; button_color=&#8221;default&#8221; button_color_hover=&#8221;#3300ff&#8221; text_color=&#8221;#3300ff&#8221; text_color_hover=&#8221;#ffffff&#8221; button_border_color=&#8221;#3300ff&#8221; button_border_color_hover=&#8221;#3300ff&#8221; button_border_thickness=&#8221;2px&#8221; link_type=&#8221;new_tab&#8221; alignment=&#8221;left&#8221; alignment_tablet=&#8221;default&#8221; alignment_phone=&#8221;default&#8221; constrain_group_1=&#8221;yes&#8221; constrain_group_3=&#8221;yes&#8221; constrain_group_4=&#8221;yes&#8221; display=&#8221;block&#8221; display_tablet=&#8221;inherit&#8221; display_phone=&#8221;inherit&#8221; icon_family=&#8221;none&#8221; link_text=&#8221;Documentation&#8221; padding_top=&#8221;12&#8243; padding_bottom=&#8221;12&#8243; padding_left=&#8221;32&#8243; padding_right=&#8221;32&#8243; url=&#8221;https:\/\/mcservice.mo.it\/wp-content\/uploads\/2024\/05\/Documentazione-pressa-seegerpdf.pdf&#8221; font_size_desktop=&#8221;18px&#8221; margin_top=&#8221;7px&#8221; margin_bottom=&#8221;7px&#8221;][\/vc_column_inner][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;5\/12&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][image_with_animation image_url=&#8221;564&#8243; image_size=&#8221;full&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;Grow In&#8221; animation_easing=&#8221;default&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;zoom-crop&#8221; alignment=&#8221;center&#8221; border_radius=&#8221;5px&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; max_width=&#8221;110%&#8221; max_width_mobile=&#8221;default&#8221;][\/vc_column_inner][\/vc_row_inner][\/tab][tab icon_family=&#8221;iconsmind&#8221; title=&#8221;<br \/>\n&lt;h3&gt;Bearing installation&lt;\/h3&gt;<br \/>\n&#8221; id=&#8221;1716821561422-2&#8243; tab_id=&#8221;1716821561423-8&#8243;][vc_row_inner column_margin=&#8221;40px&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;column_reverse&#8221; column_direction_phone=&#8221;column_reverse&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;7\/12&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_column_text css=&#8221;.vc_custom_1710767132353{padding-right: 10% !important;}&#8221; text_direction=&#8221;default&#8221;]Vertical and horizontal presses for bearing installation, with hydraulic or electric movement, supplied with a number of interchangeable fitting tools, which allow you to work with various sizes of rotors and bearings. The presses can be controlled in manual or automatic mode.[\/vc_column_text][vc_column_text text_direction=&#8221;default&#8221;]\n<h6><strong><span style=\"color: #111b27;\">Vertical presses <\/span><\/strong><\/h6>\n<p> They provide for the control of the installation quota. The height of the lower table is adjustable by PLC according to the program, to meet the biometric needs of the operator and depending on the dimensions of the items to be processed. The height of the upper presser is adjusted accordingly, by program, so as to leave adequate loading space, thus reducing the approach stroke to a minimum.<br \/>\n[\/vc_column_text][divider line_type=&#8221;Full Width Line&#8221; line_thickness=&#8221;1&#8243; divider_color=&#8221;extra-color-3&#8243; custom_height=&#8221;30&#8243;][vc_column_text text_direction=&#8221;default&#8221;]\n<h6><strong><span style=\"color: #111b27;\">Horizontal presses<\/span><\/strong><\/h6>\n<p> An alternative solution to vertical presses is our horizontal press for installing bearings on rotors and shafts. In this machine, the rotor can be placed horizontally in a special cradle, which will hold it in position, for driving the bearings. The tools are supplied with the machine and interchangeable to overcome different sizes.<br \/>\n[\/vc_column_text][divider line_type=&#8221;No Line&#8221; custom_height=&#8221;30&#8243;][nectar_cta btn_style=&#8221;text-reveal-wave&#8221; heading_tag=&#8221;h1&#8243; button_color=&#8221;accent-color&#8221; button_color_hover=&#8221;#00ff99&#8243; text_color=&#8221;#111b27&#8243; text_color_hover=&#8221;#111b27&#8243; button_border_thickness=&#8221;0px&#8221; link_type=&#8221;new_tab&#8221; alignment=&#8221;left&#8221; alignment_tablet=&#8221;default&#8221; alignment_phone=&#8221;default&#8221; constrain_group_1=&#8221;yes&#8221; constrain_group_3=&#8221;yes&#8221; constrain_group_4=&#8221;yes&#8221; display=&#8221;block&#8221; display_tablet=&#8221;inherit&#8221; display_phone=&#8221;inherit&#8221; icon_family=&#8221;none&#8221; link_text=&#8221;Contact us&#8221; padding_top=&#8221;19&#8243; padding_bottom=&#8221;19&#8243; padding_left=&#8221;32&#8243; padding_right=&#8221;32&#8243; url=&#8221;https:\/\/mcservice.mo.it\/contatti\/&#8221; font_size_desktop=&#8221;18px&#8221; margin_top=&#8221;30&#8243; margin_bottom=&#8221;30&#8243;][nectar_cta btn_style=&#8221;basic&#8221; heading_tag=&#8221;h1&#8243; button_color=&#8221;default&#8221; button_color_hover=&#8221;#3300ff&#8221; text_color=&#8221;#3300ff&#8221; text_color_hover=&#8221;#ffffff&#8221; button_border_color=&#8221;#3300ff&#8221; button_border_color_hover=&#8221;#3300ff&#8221; button_border_thickness=&#8221;2px&#8221; link_type=&#8221;new_tab&#8221; alignment=&#8221;left&#8221; alignment_tablet=&#8221;default&#8221; alignment_phone=&#8221;default&#8221; constrain_group_1=&#8221;yes&#8221; constrain_group_3=&#8221;yes&#8221; constrain_group_4=&#8221;yes&#8221; display=&#8221;block&#8221; display_tablet=&#8221;inherit&#8221; display_phone=&#8221;inherit&#8221; icon_family=&#8221;none&#8221; link_text=&#8221;Documentation&#8221; padding_top=&#8221;12&#8243; padding_bottom=&#8221;12&#8243; padding_left=&#8221;32&#8243; padding_right=&#8221;32&#8243; url=&#8221;https:\/\/mcservice.mo.it\/wp-content\/uploads\/2024\/05\/Documentazione-pressa-orizzontale.pdf&#8221; font_size_desktop=&#8221;18px&#8221; margin_top=&#8221;7px&#8221; margin_bottom=&#8221;7px&#8221;][\/vc_column_inner][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;5\/12&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][image_with_animation image_url=&#8221;565&#8243; image_size=&#8221;full&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;Grow In&#8221; animation_easing=&#8221;default&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;zoom-crop&#8221; alignment=&#8221;center&#8221; border_radius=&#8221;5px&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; max_width=&#8221;110%&#8221; max_width_mobile=&#8221;default&#8221;][\/vc_column_inner][\/vc_row_inner][\/tab][tab icon_family=&#8221;iconsmind&#8221; title=&#8221;<br \/>\n&lt;h3&gt;Fan installation&lt;\/h3&gt;<br \/>\n&#8221; id=&#8221;1716821561723-7&#8243; tab_id=&#8221;1716821561725-4&#8243;][vc_row_inner column_margin=&#8221;40px&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;column_reverse&#8221; column_direction_phone=&#8221;column_reverse&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;7\/12&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_column_text css=&#8221;.vc_custom_1710430227524{padding-right: 10% !important;}&#8221; text_direction=&#8221;default&#8221;]Multifunction insertion station for installing fans, bearings, oil seals and shields.<br \/>\n[\/vc_column_text][divider line_type=&#8221;No Line&#8221; custom_height=&#8221;30&#8243;][vc_column_text text_direction=&#8221;default&#8221;]\n<h6><strong><span style=\"color: #111b27;\">Multifunction <\/span><\/strong><\/h6>\n<p> The station can work on a self-learning function or based on pre-entered data. The interchangeability of the equipment allows the fitting of bearings, oil seals and fans. The axes of the installation zones are independent. The machine is equipped with a touchscreen monitor through which it is possible to enter the work program to be carried out or modify the operating parameters. For greater ergonomics, the height of the work area is adjustable.<br \/>\n[\/vc_column_text][nectar_cta btn_style=&#8221;text-reveal-wave&#8221; heading_tag=&#8221;h1&#8243; button_color=&#8221;accent-color&#8221; button_color_hover=&#8221;#00ff99&#8243; text_color=&#8221;#111b27&#8243; text_color_hover=&#8221;#111b27&#8243; button_border_thickness=&#8221;0px&#8221; link_type=&#8221;new_tab&#8221; alignment=&#8221;left&#8221; alignment_tablet=&#8221;default&#8221; alignment_phone=&#8221;default&#8221; constrain_group_1=&#8221;yes&#8221; constrain_group_3=&#8221;yes&#8221; constrain_group_4=&#8221;yes&#8221; display=&#8221;block&#8221; display_tablet=&#8221;inherit&#8221; display_phone=&#8221;inherit&#8221; icon_family=&#8221;none&#8221; link_text=&#8221;Contact us&#8221; padding_top=&#8221;19&#8243; padding_bottom=&#8221;19&#8243; padding_left=&#8221;32&#8243; padding_right=&#8221;32&#8243; url=&#8221;https:\/\/mcservice.mo.it\/contatti\/&#8221; font_size_desktop=&#8221;18px&#8221; margin_top=&#8221;30&#8243; margin_bottom=&#8221;30&#8243;][nectar_cta btn_style=&#8221;basic&#8221; heading_tag=&#8221;h1&#8243; button_color=&#8221;default&#8221; button_color_hover=&#8221;#3300ff&#8221; text_color=&#8221;#3300ff&#8221; text_color_hover=&#8221;#ffffff&#8221; button_border_color=&#8221;#3300ff&#8221; button_border_color_hover=&#8221;#3300ff&#8221; button_border_thickness=&#8221;2px&#8221; link_type=&#8221;new_tab&#8221; alignment=&#8221;left&#8221; alignment_tablet=&#8221;default&#8221; alignment_phone=&#8221;default&#8221; constrain_group_1=&#8221;yes&#8221; constrain_group_3=&#8221;yes&#8221; constrain_group_4=&#8221;yes&#8221; display=&#8221;block&#8221; display_tablet=&#8221;inherit&#8221; display_phone=&#8221;inherit&#8221; icon_family=&#8221;none&#8221; link_text=&#8221;Documentation&#8221; padding_top=&#8221;12&#8243; padding_bottom=&#8221;12&#8243; padding_left=&#8221;32&#8243; padding_right=&#8221;32&#8243; url=&#8221;https:\/\/mcservice.mo.it\/wp-content\/uploads\/2024\/05\/Documentazione-pressa-piantaggio-ventole.pdf&#8221; font_size_desktop=&#8221;18px&#8221; margin_top=&#8221;7px&#8221; margin_bottom=&#8221;7px&#8221;][\/vc_column_inner][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;5\/12&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][image_with_animation image_url=&#8221;499&#8243; image_size=&#8221;full&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;Grow In&#8221; animation_easing=&#8221;default&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;zoom-crop&#8221; alignment=&#8221;center&#8221; border_radius=&#8221;5px&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; max_width=&#8221;110%&#8221; max_width_mobile=&#8221;default&#8221;][\/vc_column_inner][\/vc_row_inner][\/tab][\/tabbed_section][divider line_type=&#8221;No Line&#8221; custom_height=&#8221;0&#8243; custom_height_phone=&#8221;50&#8243;][nectar_highlighted_text color_type=&#8221;regular&#8221; highlight_color=&#8221;#3300ff&#8221; text_color=&#8221;#111b27&#8243; style=&#8221;regular_underline&#8221; highlight_expansion=&#8221;default&#8221; underline_thickness=&#8221;2px&#8221; text_direction=&#8221;default&#8221;]\n<h5 style=\"text-align: center;\">We offer innovative and customized solutions for the industry, from <strong>presses<\/strong> to <em><a href=\"#presapezzo\">piece gripping<\/a><\/em> technology, from <a href=\"#speciali\"><em>special machines<\/em><\/a> to <a href=\"#lean\"><em>production lines<\/em><\/a><\/h5>\n[\/nectar_highlighted_text][divider line_type=&#8221;No Line&#8221; custom_height=&#8221;0&#8243; custom_height_phone=&#8221;50&#8243;][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_color=&#8221;rgba(242,242,242,0.6)&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;6%&#8221; bottom_padding=&#8221;6%&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; id=&#8221;presapezzo&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; shape_type=&#8221;&#8221; gradient_type=&#8221;default&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221; offset=&#8221;vc_hidden-sm vc_hidden-xs&#8221;][divider line_type=&#8221;No Line&#8221; custom_height=&#8221;0&#8243; custom_height_phone=&#8221;50&#8243;][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; left_padding_desktop=&#8221;4%&#8221; constrain_group_2=&#8221;yes&#8221; right_padding_desktop=&#8221;4%&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; centered_text=&#8221;true&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][vc_column_text text_direction=&#8221;default&#8221;]\n<h3 style=\"text-align: center;\"><strong><span style=\"color: #111b27;\">Workpiece gripping technology<\/span><\/strong><\/h3>\n[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; top_padding=&#8221;10&#8243; left_padding_desktop=&#8221;4%&#8221; constrain_group_2=&#8221;yes&#8221; right_padding_desktop=&#8221;4%&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; centered_text=&#8221;true&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][nectar_cta btn_style=&#8221;text-reveal-wave&#8221; heading_tag=&#8221;h1&#8243; button_color=&#8221;accent-color&#8221; button_color_hover=&#8221;#00ff99&#8243; text_color=&#8221;#111b27&#8243; text_color_hover=&#8221;#111b27&#8243; button_border_thickness=&#8221;0px&#8221; link_type=&#8221;new_tab&#8221; alignment=&#8221;center&#8221; alignment_tablet=&#8221;default&#8221; alignment_phone=&#8221;default&#8221; constrain_group_3=&#8221;yes&#8221; constrain_group_4=&#8221;yes&#8221; display=&#8221;inline&#8221; display_tablet=&#8221;inherit&#8221; display_phone=&#8221;inherit&#8221; icon_family=&#8221;none&#8221; link_text=&#8221;Contact us&#8221; padding_top=&#8221;19&#8243; padding_bottom=&#8221;19&#8243; padding_left=&#8221;32&#8243; padding_right=&#8221;32&#8243; url=&#8221;https:\/\/mcservice.mo.it\/contatti\/&#8221; font_size_desktop=&#8221;18px&#8221; margin_top=&#8221;7px&#8221; margin_bottom=&#8221;7px&#8221; margin_left=&#8221;0&#8243; margin_right=&#8221;10px&#8221;][divider line_type=&#8221;No Line&#8221; custom_height=&#8221;70&#8243;][\/vc_column_inner][\/vc_row_inner][vc_row_inner disable_element=&#8221;yes&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; top_padding=&#8221;20&#8243; left_padding_desktop=&#8221;4%&#8221; constrain_group_2=&#8221;yes&#8221; right_padding_desktop=&#8221;4%&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; centered_text=&#8221;true&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][nectar_cta btn_style=&#8221;text-reveal-wave&#8221; heading_tag=&#8221;h1&#8243; button_color=&#8221;accent-color&#8221; button_color_hover=&#8221;#00ff99&#8243; text_color=&#8221;#111b27&#8243; text_color_hover=&#8221;#111b27&#8243; button_border_thickness=&#8221;0px&#8221; link_type=&#8221;new_tab&#8221; alignment=&#8221;center&#8221; alignment_tablet=&#8221;default&#8221; alignment_phone=&#8221;default&#8221; constrain_group_3=&#8221;yes&#8221; constrain_group_4=&#8221;yes&#8221; display=&#8221;inline&#8221; display_tablet=&#8221;inherit&#8221; display_phone=&#8221;inherit&#8221; icon_family=&#8221;none&#8221; link_text=&#8221;Contact us&#8221; padding_top=&#8221;19&#8243; padding_bottom=&#8221;19&#8243; padding_left=&#8221;32&#8243; padding_right=&#8221;32&#8243; url=&#8221;https:\/\/mcservice.mo.it\/contatti\/&#8221; font_size_desktop=&#8221;18px&#8221; margin_top=&#8221;7px&#8221; margin_bottom=&#8221;7px&#8221; margin_left=&#8221;0&#8243; margin_right=&#8221;10px&#8221;][nectar_cta btn_style=&#8221;basic&#8221; heading_tag=&#8221;h1&#8243; button_color=&#8221;default&#8221; button_color_hover=&#8221;#3300ff&#8221; text_color=&#8221;#3300ff&#8221; text_color_hover=&#8221;#ffffff&#8221; button_border_color=&#8221;#3300ff&#8221; button_border_color_hover=&#8221;#3300ff&#8221; button_border_thickness=&#8221;2px&#8221; link_type=&#8221;new_tab&#8221; alignment=&#8221;center&#8221; alignment_tablet=&#8221;default&#8221; alignment_phone=&#8221;default&#8221; constrain_group_1=&#8221;yes&#8221; constrain_group_3=&#8221;yes&#8221; constrain_group_4=&#8221;yes&#8221; display=&#8221;inline&#8221; display_tablet=&#8221;inherit&#8221; display_phone=&#8221;inherit&#8221; icon_family=&#8221;none&#8221; link_text=&#8221;Documentation&#8221; padding_top=&#8221;12&#8243; padding_bottom=&#8221;12&#8243; padding_left=&#8221;32&#8243; padding_right=&#8221;32&#8243; url=&#8221;#&#8221; font_size_desktop=&#8221;18px&#8221; margin_top=&#8221;7px&#8221; margin_bottom=&#8221;7px&#8221;][divider line_type=&#8221;No Line&#8221; custom_height=&#8221;70&#8243;][\/vc_column_inner][\/vc_row_inner][tabbed_section style=&#8221;vertical_modern&#8221; tab_color=&#8221;Extra-Color-2&#8243; vs_content_animation=&#8221;fade&#8221; vs_link_animation=&#8221;opacity&#8221; vs_navigation_alignment=&#8221;left&#8221; vs_navigation_width_2=&#8221;25%&#8221; vs_navigation_func=&#8221;default&#8221; vs_navigation_width=&#8221;regular&#8221; vs_navigation_spacing=&#8221;15px&#8221; vs_navigation_mobile_display=&#8221;visible&#8221; vs_tab_spacing=&#8221;5%&#8221;][tab icon_family=&#8221;iconsmind&#8221; title=&#8221;Machine interface bases&#8221; id=&#8221;1716821562475-10&#8243; tab_id=&#8221;1716821562476-3&#8243;][vc_row_inner column_margin=&#8221;40px&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;7\/12&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;]<div class=\"nectar-fancy-ul\" data-list-icon=\"fa fa-dot-circle-o\" data-animation=\"false\" data-animation-delay=\"0\" data-color=\"extra-color-1\" data-spacing=\"20px\" data-alignment=\"left\"> \n<ul>\n<li><strong><strong>Machine-tool interface bases with ISO\/ASA or cylindrical centering systems. <\/strong><\/strong>Control rod with thread for fitting onto the locking lung. Flower system for locking and pulling the tool shaft. Reaction for tool shank thrust.  <\/li>\n<li><strong>Tool machine interface base with item loading stroke compensation systems.<\/strong> Terminal for control rod with bayonet system for quick base change. Flower system for locking the tailstock tie rod for item centering. <\/li>\n<\/ul>\n <\/div>[divider line_type=&#8221;No Line&#8221; custom_height=&#8221;30&#8243;][\/vc_column_inner][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;5\/12&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][image_with_animation image_url=&#8221;1046&#8243; image_size=&#8221;full&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;Grow In&#8221; animation_easing=&#8221;default&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;zoom-crop&#8221; alignment=&#8221;center&#8221; border_radius=&#8221;5px&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; max_width=&#8221;110%&#8221; max_width_mobile=&#8221;default&#8221;][\/vc_column_inner][\/vc_row_inner][\/tab][tab icon_family=&#8221;iconsmind&#8221; title=&#8221;Turning tools&#8221; id=&#8221;1716821562662-0&#8243; tab_id=&#8221;1716821562662-6&#8243;][vc_row_inner column_margin=&#8221;40px&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;7\/12&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;]<div class=\"nectar-fancy-ul\" data-list-icon=\"fa fa-dot-circle-o\" data-animation=\"false\" data-animation-delay=\"0\" data-color=\"extra-color-1\" data-spacing=\"20px\" data-alignment=\"left\"> \n<ul>\n<li><strong>Self-centering clamping mandrel for turning items with ASA or cylindrical connection.<\/strong> Equipment with special jaws for turning with centering off the rotation axis. Positioning references. <\/li>\n<li><strong>Self-centering clamping mandrel for turning items with ASA or cylindrical connection.<\/strong> Equipment with special jaws for traditional turning for large diameters.<\/li>\n<li><strong>Self-centering clamping mandrel for turning items with ASA or cylindrical connection.<\/strong> Equipment with special jaws for turning with dedicated piece support with control PEL.<\/li>\n<\/ul>\n <\/div>[divider line_type=&#8221;No Line&#8221; custom_height=&#8221;30&#8243;][\/vc_column_inner][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;5\/12&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][image_with_animation image_url=&#8221;1047&#8243; image_size=&#8221;full&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;Grow In&#8221; animation_easing=&#8221;default&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;zoom-crop&#8221; alignment=&#8221;center&#8221; border_radius=&#8221;5px&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; max_width=&#8221;110%&#8221; max_width_mobile=&#8221;default&#8221;][\/vc_column_inner][\/vc_row_inner][\/tab][tab icon_family=&#8221;iconsmind&#8221; title=&#8221;Toothing tools&#8221; id=&#8221;1716821562808-10&#8243; tab_id=&#8221;1716821562808-10&#8243;][vc_row_inner column_margin=&#8221;40px&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;7\/12&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;]<div class=\"nectar-fancy-ul\" data-list-icon=\"fa fa-dot-circle-o\" data-animation=\"false\" data-animation-delay=\"0\" data-color=\"extra-color-1\" data-spacing=\"20px\" data-alignment=\"left\"> \n<ul>\n<li><strong>Clamping mandrel for toothing with shaper knife.<\/strong> ASA or cylindrical machine interface base with bayonet opening\/closing control tie rod. Elastic gripper with conical reaction for gripping external diameters. <\/li>\n<li><strong>Clamping mandrel for toothing with shaper knife.<\/strong> ASA or cylindrical machine interface base with threaded tie rod for opening\/closing control. Vulcanized conical elastic gripper for gripping external diameters.<\/li>\n<li><strong>Expanding mandrel for gear hobbing.<\/strong> ASA or cylindrical machine interface base with bayonet opening\/closing control tie rod. Elastic gripper with conical reaction for gripping internal diameters. <\/li>\n<\/ul>\n <\/div>[divider line_type=&#8221;No Line&#8221; custom_height=&#8221;30&#8243;][\/vc_column_inner][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;5\/12&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][image_with_animation image_url=&#8221;1050&#8243; image_size=&#8221;full&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;Grow In&#8221; animation_easing=&#8221;default&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;zoom-crop&#8221; alignment=&#8221;center&#8221; border_radius=&#8221;5px&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; max_width=&#8221;110%&#8221; max_width_mobile=&#8221;default&#8221;][\/vc_column_inner][\/vc_row_inner][\/tab][tab icon_family=&#8221;iconsmind&#8221; title=&#8221;Grinding tools&#8221; id=&#8221;1716821562971-10&#8243; tab_id=&#8221;1716821562972-8&#8243;][vc_row_inner column_margin=&#8221;40px&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;7\/12&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;]<div class=\"nectar-fancy-ul\" data-list-icon=\"fa fa-dot-circle-o\" data-animation=\"false\" data-animation-delay=\"0\" data-color=\"extra-color-1\" data-spacing=\"20px\" data-alignment=\"left\"> \n<ul>\n<li><strong>Elastic diaphragm clamping mandrel for item grinding.<\/strong> ASA or cylindrical machine interface base with membrane opening control tie rod. Support and jaws designed for specific item. <\/li>\n<li><strong>Item clamping mandrel using self-centering expansion gripper for tooth grinding.<\/strong> ASA or cylindrical machine interface base. Clamp opening\/closing control tie rod. <\/li>\n<li><strong>Clamping mandrel with double elastic membrane for item grinding.<\/strong> ASA or cylindrical machine interface base with membrane opening control tie rod. Support and jaws designed for specific item. <\/li>\n<\/ul>\n <\/div>[divider line_type=&#8221;No Line&#8221; custom_height=&#8221;30&#8243;][\/vc_column_inner][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;5\/12&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][image_with_animation image_url=&#8221;1048&#8243; image_size=&#8221;full&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;Grow In&#8221; animation_easing=&#8221;default&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;zoom-crop&#8221; alignment=&#8221;center&#8221; border_radius=&#8221;5px&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; max_width=&#8221;110%&#8221; max_width_mobile=&#8221;default&#8221;][\/vc_column_inner][\/vc_row_inner][\/tab][tab icon_family=&#8221;iconsmind&#8221; title=&#8221;Manipulators for anthropomorphs&#8221; id=&#8221;1716821563132-9&#8243; tab_id=&#8221;1716821563135-3&#8243;][vc_row_inner column_margin=&#8221;40px&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;7\/12&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;]<div class=\"nectar-fancy-ul\" data-list-icon=\"fa fa-dot-circle-o\" data-animation=\"false\" data-animation-delay=\"0\" data-color=\"extra-color-1\" data-spacing=\"20px\" data-alignment=\"left\"> \n<ul>\n<li><strong>Manipulation system for item tipping and handling.<\/strong> Small drawing hands for special items<\/li>\n<li><strong>Manipulation, loading and unloading and handling systems for items in general.<\/strong> Small drawing hands for special items.<\/li>\n<\/ul>\n <\/div>[divider line_type=&#8221;No Line&#8221; custom_height=&#8221;30&#8243;][\/vc_column_inner][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;5\/12&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][image_with_animation image_url=&#8221;1049&#8243; image_size=&#8221;full&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;Grow In&#8221; animation_easing=&#8221;default&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;zoom-crop&#8221; alignment=&#8221;center&#8221; border_radius=&#8221;5px&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; max_width=&#8221;110%&#8221; max_width_mobile=&#8221;default&#8221;][\/vc_column_inner][\/vc_row_inner][\/tab][tab icon_family=&#8221;iconsmind&#8221; title=&#8221;Work centers&#8221; id=&#8221;1716821563307-2&#8243; tab_id=&#8221;1716821563308-8&#8243;][vc_row_inner column_margin=&#8221;40px&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;7\/12&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;]<div class=\"nectar-fancy-ul\" data-list-icon=\"fa fa-dot-circle-o\" data-animation=\"false\" data-animation-delay=\"0\" data-color=\"extra-color-1\" data-spacing=\"20px\" data-alignment=\"left\"> \n<ul>\n<li><strong>Hydraulic vice on processing cube.<\/strong><\/li>\n<li><strong>Reference and workpiece clamping tools for pallets, processing cubes and machine benches.<\/strong><\/li>\n<li><strong>Manual, pneumatic and hydraulic locking control.<\/strong><\/li>\n<li><strong>Assembly\/disassembly and reference systems for quick, fast and precise machine setup.<\/strong><\/li>\n<li><strong>Clamping cubes and systems in general.<\/strong><\/li>\n<li><strong>Interchangeable plates for cube layout change.<\/strong><\/li>\n<li><strong>Workpiece gripping with manual and\/or hydraulic\/pneumatic clamping.<\/strong><\/li>\n<li><strong>Modular vertical locking systems.<\/strong><\/li>\n<li><strong>Solutions for division into phases and multi-processing.<\/strong><\/li>\n<li><strong>Piece presence check systems.<\/strong><\/li>\n<\/ul>\n <\/div>[divider line_type=&#8221;No Line&#8221; custom_height=&#8221;30&#8243;][\/vc_column_inner][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;5\/12&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][image_with_animation image_url=&#8221;1041&#8243; image_size=&#8221;full&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;Grow In&#8221; animation_easing=&#8221;default&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;zoom-crop&#8221; alignment=&#8221;center&#8221; border_radius=&#8221;5px&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; max_width=&#8221;110%&#8221; max_width_mobile=&#8221;default&#8221;][\/vc_column_inner][\/vc_row_inner][\/tab][\/tabbed_section][nectar_highlighted_text color_type=&#8221;regular&#8221; highlight_color=&#8221;#3300ff&#8221; text_color=&#8221;#111b27&#8243; style=&#8221;regular_underline&#8221; highlight_expansion=&#8221;default&#8221; underline_thickness=&#8221;2px&#8221; text_direction=&#8221;default&#8221;]\n<h5 style=\"text-align: center;\">We offer innovative and customized solutions for the industry, from <em><a href=\"#presse\">presses<\/a><\/em> to <strong>piece gripping<\/strong> technology, from s<a href=\"#speciali\"><em>pecial machines <\/em><\/a>to <a href=\"#lean\"><em>production lines<\/em><\/a><\/h5>\n[\/nectar_highlighted_text][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221; offset=&#8221;vc_hidden-lg vc_hidden-md&#8221;][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; left_padding_desktop=&#8221;4%&#8221; constrain_group_2=&#8221;yes&#8221; right_padding_desktop=&#8221;4%&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; centered_text=&#8221;true&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][vc_column_text text_direction=&#8221;default&#8221;]\n<h3 style=\"text-align: center;\"><strong><span style=\"color: #111b27;\">Workpiece gripping technology<\/span><\/strong><\/h3>\n[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; top_padding=&#8221;10&#8243; left_padding_desktop=&#8221;4%&#8221; constrain_group_2=&#8221;yes&#8221; right_padding_desktop=&#8221;4%&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; centered_text=&#8221;true&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][nectar_cta btn_style=&#8221;text-reveal-wave&#8221; heading_tag=&#8221;h1&#8243; button_color=&#8221;accent-color&#8221; button_color_hover=&#8221;#00ff99&#8243; text_color=&#8221;#111b27&#8243; text_color_hover=&#8221;#111b27&#8243; button_border_thickness=&#8221;0px&#8221; link_type=&#8221;new_tab&#8221; alignment=&#8221;center&#8221; alignment_tablet=&#8221;default&#8221; alignment_phone=&#8221;default&#8221; constrain_group_3=&#8221;yes&#8221; constrain_group_4=&#8221;yes&#8221; display=&#8221;inline&#8221; display_tablet=&#8221;inherit&#8221; display_phone=&#8221;inherit&#8221; icon_family=&#8221;none&#8221; link_text=&#8221;Contact us&#8221; padding_top=&#8221;19&#8243; padding_bottom=&#8221;19&#8243; padding_left=&#8221;32&#8243; padding_right=&#8221;32&#8243; url=&#8221;https:\/\/mcservice.mo.it\/contatti\/&#8221; font_size_desktop=&#8221;18px&#8221; margin_top=&#8221;7px&#8221; margin_bottom=&#8221;7px&#8221; margin_left=&#8221;0&#8243; margin_right=&#8221;10px&#8221;][divider line_type=&#8221;No Line&#8221; custom_height=&#8221;70&#8243;][\/vc_column_inner][\/vc_row_inner][vc_row_inner disable_element=&#8221;yes&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; top_padding=&#8221;20&#8243; left_padding_desktop=&#8221;4%&#8221; constrain_group_2=&#8221;yes&#8221; right_padding_desktop=&#8221;4%&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; centered_text=&#8221;true&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][nectar_cta btn_style=&#8221;text-reveal-wave&#8221; heading_tag=&#8221;h1&#8243; button_color=&#8221;accent-color&#8221; button_color_hover=&#8221;#00ff99&#8243; text_color=&#8221;#111b27&#8243; text_color_hover=&#8221;#111b27&#8243; button_border_thickness=&#8221;0px&#8221; link_type=&#8221;new_tab&#8221; alignment=&#8221;center&#8221; alignment_tablet=&#8221;default&#8221; alignment_phone=&#8221;default&#8221; constrain_group_3=&#8221;yes&#8221; constrain_group_4=&#8221;yes&#8221; display=&#8221;inline&#8221; display_tablet=&#8221;inherit&#8221; display_phone=&#8221;inherit&#8221; icon_family=&#8221;none&#8221; link_text=&#8221;Contact us&#8221; padding_top=&#8221;19&#8243; padding_bottom=&#8221;19&#8243; padding_left=&#8221;32&#8243; padding_right=&#8221;32&#8243; url=&#8221;https:\/\/mcservice.mo.it\/contatti\/&#8221; font_size_desktop=&#8221;18px&#8221; margin_top=&#8221;7px&#8221; margin_bottom=&#8221;7px&#8221; margin_left=&#8221;0&#8243; margin_right=&#8221;10px&#8221;][nectar_cta btn_style=&#8221;basic&#8221; heading_tag=&#8221;h1&#8243; button_color=&#8221;default&#8221; button_color_hover=&#8221;#3300ff&#8221; text_color=&#8221;#3300ff&#8221; text_color_hover=&#8221;#ffffff&#8221; button_border_color=&#8221;#3300ff&#8221; button_border_color_hover=&#8221;#3300ff&#8221; button_border_thickness=&#8221;2px&#8221; link_type=&#8221;new_tab&#8221; alignment=&#8221;center&#8221; alignment_tablet=&#8221;default&#8221; alignment_phone=&#8221;default&#8221; constrain_group_1=&#8221;yes&#8221; constrain_group_3=&#8221;yes&#8221; constrain_group_4=&#8221;yes&#8221; display=&#8221;inline&#8221; display_tablet=&#8221;inherit&#8221; display_phone=&#8221;inherit&#8221; icon_family=&#8221;none&#8221; link_text=&#8221;Documentation&#8221; padding_top=&#8221;12&#8243; padding_bottom=&#8221;12&#8243; padding_left=&#8221;32&#8243; padding_right=&#8221;32&#8243; url=&#8221;#&#8221; font_size_desktop=&#8221;18px&#8221; margin_top=&#8221;7px&#8221; margin_bottom=&#8221;7px&#8221;][divider line_type=&#8221;No Line&#8221; custom_height=&#8221;70&#8243;][\/vc_column_inner][\/vc_row_inner][tabbed_section style=&#8221;vertical_scrolling&#8221; tab_color=&#8221;Extra-Color-2&#8243; vs_navigation_func=&#8221;default&#8221; vs_navigation_width=&#8221;regular&#8221; vs_navigation_spacing=&#8221;15px&#8221; vs_navigation_mobile_display=&#8221;visible&#8221; vs_tab_spacing=&#8221;10%&#8221; vs_tab_tag=&#8221;p&#8221; vs_cta_style=&#8221;see-through&#8221; vs_cta_bg_color=&#8221;default&#8221; vs_cta_heading_tag=&#8221;h6&#8243; vs_sticky_aspect=&#8221;default&#8221;][tab icon_family=&#8221;iconsmind&#8221; title=&#8221;<br \/>\n&lt;h3&gt;Machine interface bases&lt;\/h3&gt;<br \/>\n&#8221; id=&#8221;1716821564002-6&#8243; tab_id=&#8221;1716821564004-0&#8243;][vc_row_inner column_margin=&#8221;40px&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;7\/12&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;]<div class=\"nectar-fancy-ul\" data-list-icon=\"fa fa-dot-circle-o\" data-animation=\"false\" data-animation-delay=\"0\" data-color=\"extra-color-1\" data-spacing=\"20px\" data-alignment=\"left\"> \n<ul>\n<li><strong><strong>Machine-tool interface bases with ISO\/ASA or cylindrical centering systems. <\/strong><\/strong>Control rod with thread for fitting onto the locking lung. Flower system for locking and pulling the tool shaft. Reaction for tool shank thrust.  <\/li>\n<li><strong>Tool machine interface base with item loading stroke compensation systems.<\/strong> Terminal for control rod with bayonet system for quick base change. Flower system for locking the tailstock tie rod for item centering. <\/li>\n<\/ul>\n <\/div>[divider line_type=&#8221;No Line&#8221; custom_height=&#8221;30&#8243;][\/vc_column_inner][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;5\/12&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][image_with_animation image_url=&#8221;1046&#8243; image_size=&#8221;full&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;Grow In&#8221; animation_easing=&#8221;default&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;zoom-crop&#8221; alignment=&#8221;center&#8221; border_radius=&#8221;5px&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; max_width=&#8221;110%&#8221; max_width_mobile=&#8221;default&#8221;][\/vc_column_inner][\/vc_row_inner][\/tab][tab icon_family=&#8221;iconsmind&#8221; title=&#8221;<br \/>\n&lt;h3&gt;Turning tools&lt;\/h3&gt;<br \/>\n&#8221; id=&#8221;1716821564222-3&#8243; tab_id=&#8221;1716821564222-1&#8243;][vc_row_inner column_margin=&#8221;40px&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;7\/12&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;]<div class=\"nectar-fancy-ul\" data-list-icon=\"fa fa-dot-circle-o\" data-animation=\"false\" data-animation-delay=\"0\" data-color=\"extra-color-1\" data-spacing=\"20px\" data-alignment=\"left\"> \n<ul>\n<li><strong>Self-centering clamping mandrel for turning items with ASA or cylindrical connection.<\/strong> Equipment with special jaws for turning with centering off the rotation axis. Positioning references. <\/li>\n<li><strong>Self-centering clamping mandrel for turning items with ASA or cylindrical connection.<\/strong> Equipment with special jaws for traditional turning for large diameters.<\/li>\n<li><strong>Self-centering clamping mandrel for turning items with ASA or cylindrical connection.<\/strong> Equipment with special jaws for turning with dedicated piece support with control PEL.<\/li>\n<\/ul>\n <\/div>[divider line_type=&#8221;No Line&#8221; custom_height=&#8221;30&#8243;][\/vc_column_inner][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;5\/12&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][image_with_animation image_url=&#8221;1047&#8243; image_size=&#8221;full&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;Grow In&#8221; animation_easing=&#8221;default&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;zoom-crop&#8221; alignment=&#8221;center&#8221; border_radius=&#8221;5px&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; max_width=&#8221;110%&#8221; max_width_mobile=&#8221;default&#8221;][\/vc_column_inner][\/vc_row_inner][\/tab][tab icon_family=&#8221;iconsmind&#8221; title=&#8221;<br \/>\n&lt;h3&gt;Toothing tools&lt;\/h3&gt;<br \/>\n&#8221; id=&#8221;1716821564387-1&#8243; tab_id=&#8221;1716821564388-3&#8243;][vc_row_inner column_margin=&#8221;40px&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;7\/12&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;]<div class=\"nectar-fancy-ul\" data-list-icon=\"fa fa-dot-circle-o\" data-animation=\"false\" data-animation-delay=\"0\" data-color=\"extra-color-1\" data-spacing=\"20px\" data-alignment=\"left\"> \n<ul>\n<li><strong>Clamping mandrel for toothing with shaper knife.<\/strong> ASA or cylindrical machine interface base with bayonet opening\/closing control tie rod. Elastic gripper with conical reaction for gripping external diameters. <\/li>\n<li><strong>Clamping mandrel for toothing with shaper knife.<\/strong> ASA or cylindrical machine interface base with threaded tie rod for opening\/closing control. Vulcanized conical elastic gripper for gripping external diameters.<\/li>\n<li><strong>Expanding mandrel for gear hobbing.<\/strong> ASA or cylindrical machine interface base with bayonet opening\/closing control tie rod. Elastic gripper with conical reaction for gripping internal diameters. <\/li>\n<\/ul>\n <\/div>[divider line_type=&#8221;No Line&#8221; custom_height=&#8221;30&#8243;][\/vc_column_inner][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;5\/12&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][image_with_animation image_url=&#8221;1050&#8243; image_size=&#8221;full&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;Grow In&#8221; animation_easing=&#8221;default&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;zoom-crop&#8221; alignment=&#8221;center&#8221; border_radius=&#8221;5px&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; max_width=&#8221;110%&#8221; max_width_mobile=&#8221;default&#8221;][\/vc_column_inner][\/vc_row_inner][\/tab][tab icon_family=&#8221;iconsmind&#8221; title=&#8221;<br \/>\n&lt;h3&gt;Grinding tools&lt;\/h3&gt;<br \/>\n&#8221; id=&#8221;1716821564572-9&#8243; tab_id=&#8221;1716821564573-3&#8243;][vc_row_inner column_margin=&#8221;40px&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;7\/12&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;]<div class=\"nectar-fancy-ul\" data-list-icon=\"fa fa-dot-circle-o\" data-animation=\"false\" data-animation-delay=\"0\" data-color=\"extra-color-1\" data-spacing=\"20px\" data-alignment=\"left\"> \n<ul>\n<li><strong>Elastic diaphragm clamping mandrel for item grinding.<\/strong> ASA or cylindrical machine interface base with membrane opening control tie rod. Support and jaws designed for specific item. <\/li>\n<li><strong>Item clamping mandrel using self-centering expansion gripper for tooth grinding.<\/strong> ASA or cylindrical machine interface base. Clamp opening\/closing control tie rod. <\/li>\n<li><strong>Clamping mandrel with double elastic membrane for item grinding.<\/strong> ASA or cylindrical machine interface base with membrane opening control tie rod. Support and jaws designed for specific item. <\/li>\n<\/ul>\n <\/div>[divider line_type=&#8221;No Line&#8221; custom_height=&#8221;30&#8243;][\/vc_column_inner][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;5\/12&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][image_with_animation image_url=&#8221;1048&#8243; image_size=&#8221;full&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;Grow In&#8221; animation_easing=&#8221;default&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;zoom-crop&#8221; alignment=&#8221;center&#8221; border_radius=&#8221;5px&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; max_width=&#8221;110%&#8221; max_width_mobile=&#8221;default&#8221;][\/vc_column_inner][\/vc_row_inner][\/tab][tab icon_family=&#8221;iconsmind&#8221; title=&#8221;<br \/>\n&lt;h3&gt;Manipulators for anthropomorphs&lt;\/h3&gt;<br \/>\n&#8221; id=&#8221;1716821564786-5&#8243; tab_id=&#8221;1716821564787-2&#8243;][vc_row_inner column_margin=&#8221;40px&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;7\/12&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;]<div class=\"nectar-fancy-ul\" data-list-icon=\"fa fa-dot-circle-o\" data-animation=\"false\" data-animation-delay=\"0\" data-color=\"extra-color-1\" data-spacing=\"20px\" data-alignment=\"left\"> \n<ul>\n<li><strong>Manipulation system for item tipping and handling.<\/strong> Small drawing hands for special items<\/li>\n<li><strong>Manipulation, loading and unloading and handling systems for items in general.<\/strong> Small drawing hands for special items.<\/li>\n<\/ul>\n <\/div>[divider line_type=&#8221;No Line&#8221; custom_height=&#8221;30&#8243;][\/vc_column_inner][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;5\/12&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][image_with_animation image_url=&#8221;1049&#8243; image_size=&#8221;full&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;Grow In&#8221; animation_easing=&#8221;default&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;zoom-crop&#8221; alignment=&#8221;center&#8221; border_radius=&#8221;5px&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; max_width=&#8221;110%&#8221; max_width_mobile=&#8221;default&#8221;][\/vc_column_inner][\/vc_row_inner][\/tab][tab icon_family=&#8221;iconsmind&#8221; title=&#8221;<br \/>\n&lt;h3&gt;Work centers&lt;\/h3&gt;<br \/>\n&#8221; id=&#8221;1716821564990-6&#8243; tab_id=&#8221;1716821564991-3&#8243;][vc_row_inner column_margin=&#8221;40px&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;7\/12&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;]<div class=\"nectar-fancy-ul\" data-list-icon=\"fa fa-dot-circle-o\" data-animation=\"false\" data-animation-delay=\"0\" data-color=\"extra-color-1\" data-spacing=\"20px\" data-alignment=\"left\"> \n<ul>\n<li><strong>Hydraulic vice on processing cube.<\/strong><\/li>\n<li><strong>Reference and workpiece clamping tools for pallets, processing cubes and machine benches.<\/strong><\/li>\n<li><strong>Manual, pneumatic and hydraulic locking control.<\/strong><\/li>\n<li><strong>Assembly\/disassembly and reference systems for quick, fast and precise machine setup.<\/strong><\/li>\n<li><strong>Clamping cubes and systems in general.<\/strong><\/li>\n<li><strong>Interchangeable plates for cube layout change.<\/strong><\/li>\n<li><strong>Workpiece gripping with manual and\/or hydraulic\/pneumatic clamping.<\/strong><\/li>\n<li><strong>Modular vertical locking systems.<\/strong><\/li>\n<li><strong>Solutions for division into phases and multi-processing.<\/strong><\/li>\n<li><strong>Piece presence check systems.<\/strong><\/li>\n<\/ul>\n <\/div>[divider line_type=&#8221;No Line&#8221; custom_height=&#8221;30&#8243;][\/vc_column_inner][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;5\/12&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][image_with_animation image_url=&#8221;1041&#8243; image_size=&#8221;full&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;Grow In&#8221; animation_easing=&#8221;default&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;zoom-crop&#8221; alignment=&#8221;center&#8221; border_radius=&#8221;5px&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; max_width=&#8221;110%&#8221; max_width_mobile=&#8221;default&#8221;][\/vc_column_inner][\/vc_row_inner][\/tab][\/tabbed_section][divider line_type=&#8221;No Line&#8221; custom_height=&#8221;0&#8243; custom_height_phone=&#8221;50&#8243;][nectar_highlighted_text color_type=&#8221;regular&#8221; highlight_color=&#8221;#3300ff&#8221; text_color=&#8221;#111b27&#8243; style=&#8221;regular_underline&#8221; highlight_expansion=&#8221;default&#8221; underline_thickness=&#8221;2px&#8221; text_direction=&#8221;default&#8221;]\n<h5 style=\"text-align: center;\">We offer innovative and customized solutions for the industry, from <em><a href=\"#presse\">presses<\/a><\/em> to <strong>piece gripping<\/strong> technology, from s<a href=\"#speciali\"><em>pecial machines <\/em><\/a>to <a href=\"#lean\"><em>production lines<\/em><\/a><\/h5>\n[\/nectar_highlighted_text][divider line_type=&#8221;No Line&#8221; custom_height=&#8221;0&#8243; custom_height_phone=&#8221;50&#8243;][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_color=&#8221;rgba(255,255,255,0.9)&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;7%&#8221; bottom_padding=&#8221;6%&#8221; left_padding_desktop=&#8221;15%&#8221; constrain_group_2=&#8221;yes&#8221; right_padding_desktop=&#8221;15%&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; id=&#8221;speciali&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; left_padding_desktop=&#8221;4%&#8221; constrain_group_2=&#8221;yes&#8221; right_padding_desktop=&#8221;4%&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; centered_text=&#8221;true&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][divider line_type=&#8221;No Line&#8221; custom_height=&#8221;0&#8243; custom_height_phone=&#8221;50&#8243;][vc_column_text text_direction=&#8221;default&#8221;]\n<h3 style=\"text-align: center;\"><strong><span style=\"color: #111b27;\">Special machines<\/span><\/strong><\/h3>\n[\/vc_column_text][divider line_type=&#8221;No Line&#8221; custom_height=&#8221;20&#8243;][vc_column_text text_direction=&#8221;default&#8221;]\n<p style=\"text-align: center;\">Special machines for the production of RFiDs, unloading arms and lifters for the food sector, machines for sampling feed, from silos, tanks and storage systems<\/p>\n[\/vc_column_text][divider line_type=&#8221;No Line&#8221; custom_height=&#8221;20&#8243;][nectar_cta btn_style=&#8221;basic&#8221; heading_tag=&#8221;h1&#8243; button_color=&#8221;default&#8221; button_color_hover=&#8221;#3300ff&#8221; text_color=&#8221;#3300ff&#8221; text_color_hover=&#8221;#ffffff&#8221; button_border_color=&#8221;#3300ff&#8221; button_border_color_hover=&#8221;#3300ff&#8221; button_border_thickness=&#8221;2px&#8221; link_type=&#8221;new_tab&#8221; alignment=&#8221;center&#8221; alignment_tablet=&#8221;default&#8221; alignment_phone=&#8221;default&#8221; constrain_group_3=&#8221;yes&#8221; constrain_group_4=&#8221;yes&#8221; display=&#8221;block&#8221; display_tablet=&#8221;inherit&#8221; display_phone=&#8221;inherit&#8221; icon_family=&#8221;none&#8221; link_text=&#8221;Documentation&#8221; padding_top=&#8221;12&#8243; padding_bottom=&#8221;12&#8243; padding_left=&#8221;32&#8243; padding_right=&#8221;32&#8243; url=&#8221;https:\/\/mcservice.mo.it\/wp-content\/uploads\/2024\/05\/presentazione-generale_macchine-speciali.pdf&#8221; font_size_desktop=&#8221;18px&#8221; margin_top=&#8221;30&#8243; margin_bottom=&#8221;7px&#8221;][divider line_type=&#8221;No Line&#8221; custom_height=&#8221;60&#8243;][\/vc_column_inner][\/vc_row_inner][vc_gallery type=&#8221;flickity_static_height_style&#8221; images=&#8221;998,999,1000,1001,1002&#8243; flickity_spacing=&#8221;15px&#8221; flickity_controls=&#8221;material_pagination&#8221; flickity_overflow=&#8221;visible&#8221; flickity_wrap_around=&#8221;wrap&#8221; flickity_image_parallax=&#8221;true&#8221; flickity_autoplay=&#8221;true&#8221; flickity_box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; onclick=&#8221;link_no&#8221; img_size=&#8221;full&#8221; flickity_img_height=&#8221;400&#8243; flickity_autoplay_dur=&#8221;4000&#8243;][divider line_type=&#8221;No Line&#8221; custom_height=&#8221;0&#8243; custom_height_phone=&#8221;50&#8243;][nectar_highlighted_text color_type=&#8221;regular&#8221; highlight_color=&#8221;#3300ff&#8221; text_color=&#8221;#111b27&#8243; style=&#8221;regular_underline&#8221; highlight_expansion=&#8221;default&#8221; underline_thickness=&#8221;2px&#8221; text_direction=&#8221;default&#8221;]\n<h5 style=\"text-align: center;\">We offer innovative and customized solutions for the industry, from <em><a href=\"#presse\">presses<\/a><\/em> to <em><a href=\"#presapezzo\">piece gripping<\/a><\/em> technology, from <strong>special machines<\/strong> to <a href=\"#lean\"><em>production lines<\/em><\/a><\/h5>\n[\/nectar_highlighted_text][divider line_type=&#8221;No Line&#8221; custom_height=&#8221;0&#8243; custom_height_phone=&#8221;50&#8243;][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_color=&#8221;rgba(242,242,242,0.6)&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;7%&#8221; bottom_padding=&#8221;6%&#8221; left_padding_desktop=&#8221;15%&#8221; constrain_group_2=&#8221;yes&#8221; right_padding_desktop=&#8221;15%&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; id=&#8221;lean&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; left_padding_desktop=&#8221;4%&#8221; constrain_group_2=&#8221;yes&#8221; right_padding_desktop=&#8221;4%&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; centered_text=&#8221;true&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][divider line_type=&#8221;No Line&#8221; custom_height=&#8221;0&#8243; custom_height_phone=&#8221;50&#8243;][vc_column_text text_direction=&#8221;default&#8221;]\n<h3 style=\"text-align: center;\"><strong><span style=\"color: #111b27;\">Lean production<\/span><\/strong><\/h3>\n[\/vc_column_text][divider line_type=&#8221;No Line&#8221; custom_height=&#8221;20&#8243;][vc_column_text text_direction=&#8221;default&#8221;]\n<p style=\"text-align: center;\">Tipping benches, assembly benches, serving carriages and layout design<\/p>\n[\/vc_column_text][divider line_type=&#8221;No Line&#8221; custom_height=&#8221;20&#8243;][nectar_cta btn_style=&#8221;basic&#8221; heading_tag=&#8221;h1&#8243; button_color=&#8221;default&#8221; button_color_hover=&#8221;#3300ff&#8221; text_color=&#8221;#3300ff&#8221; text_color_hover=&#8221;#ffffff&#8221; button_border_color=&#8221;#3300ff&#8221; button_border_color_hover=&#8221;#3300ff&#8221; button_border_thickness=&#8221;2px&#8221; link_type=&#8221;new_tab&#8221; alignment=&#8221;center&#8221; alignment_tablet=&#8221;default&#8221; alignment_phone=&#8221;default&#8221; constrain_group_3=&#8221;yes&#8221; constrain_group_4=&#8221;yes&#8221; display=&#8221;block&#8221; display_tablet=&#8221;inherit&#8221; display_phone=&#8221;inherit&#8221; icon_family=&#8221;none&#8221; link_text=&#8221;Documentation&#8221; padding_top=&#8221;12&#8243; padding_bottom=&#8221;12&#8243; padding_left=&#8221;32&#8243; padding_right=&#8221;32&#8243; url=&#8221;https:\/\/mcservice.mo.it\/wp-content\/uploads\/2024\/05\/presentazione-generale_lean-production.pdf&#8221; font_size_desktop=&#8221;18px&#8221; margin_top=&#8221;30&#8243; margin_bottom=&#8221;7px&#8221;][divider line_type=&#8221;No Line&#8221; custom_height=&#8221;60&#8243;][\/vc_column_inner][\/vc_row_inner][vc_gallery type=&#8221;flickity_static_height_style&#8221; images=&#8221;1007,1008,1009,1010,1011&#8243; flickity_spacing=&#8221;15px&#8221; flickity_controls=&#8221;material_pagination&#8221; flickity_overflow=&#8221;visible&#8221; flickity_wrap_around=&#8221;wrap&#8221; flickity_image_parallax=&#8221;true&#8221; flickity_autoplay=&#8221;true&#8221; flickity_box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; onclick=&#8221;link_no&#8221; img_size=&#8221;full&#8221; flickity_img_height=&#8221;400&#8243;][nectar_highlighted_text color_type=&#8221;regular&#8221; highlight_color=&#8221;#3300ff&#8221; text_color=&#8221;#111b27&#8243; style=&#8221;regular_underline&#8221; highlight_expansion=&#8221;default&#8221; underline_thickness=&#8221;2px&#8221; text_direction=&#8221;default&#8221;]\n<h5 style=\"text-align: center;\">We offer innovative and customized solutions for industry, from <a href=\"#presse\"><em>presses<\/em><\/a> to technology for <a href=\"#presapezzo\"><em>workpiece gripping<\/em><\/a>, from <a href=\"#speciali\"><em>special machines<\/em><\/a> to <strong>production lines<\/strong><\/h5>\n[\/nectar_highlighted_text][divider line_type=&#8221;No Line&#8221; custom_height=&#8221;0&#8243; custom_height_phone=&#8221;50&#8243;][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_color=&#8221;#ffffff&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;7%&#8221; bottom_padding=&#8221;6%&#8221; left_padding_desktop=&#8221;15%&#8221; constrain_group_2=&#8221;yes&#8221; right_padding_desktop=&#8221;15%&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; disable_element=&#8221;yes&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; left_padding_desktop=&#8221;4%&#8221; constrain_group_2=&#8221;yes&#8221; right_padding_desktop=&#8221;4%&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; centered_text=&#8221;true&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][vc_column_text text_direction=&#8221;default&#8221;]\n<h3 style=\"text-align: center;\"><strong><span style=\"color: #111b27;\">Food<\/span><\/strong><\/h3>\n[\/vc_column_text][divider line_type=&#8221;No Line&#8221; custom_height=&#8221;20&#8243;][vc_column_text text_direction=&#8221;default&#8221;]\n<p style=\"text-align: center;\">I am text block. Click edit button to change this text. Lorem ipsum dolor sit amet, consectetur adipiscing elit. Ut elit tellus, luctus nec ullamcorper mattis, pulvinar dapibus leo. I am text block. Click edit button to change this text. Lorem ipsum dolor sit amet, consectetur adipiscing elit.<\/p>\n[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][vc_gallery type=&#8221;flickity_style&#8221; flickity_spacing=&#8221;default&#8221; flickity_controls=&#8221;material_pagination&#8221; flickity_overflow=&#8221;visible&#8221; flickity_wrap_around=&#8221;wrap&#8221; flickity_desktop_columns=&#8221;1&#8243; flickity_small_desktop_columns=&#8221;1&#8243; flickity_tablet_columns=&#8221;1&#8243; flickity_phone_columns=&#8221;1&#8243; flickity_box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; onclick=&#8221;link_no&#8221; img_size=&#8221;full&#8221;][nectar_highlighted_text color_type=&#8221;regular&#8221; highlight_color=&#8221;#3300ff&#8221; text_color=&#8221;#111b27&#8243; style=&#8221;regular_underline&#8221; highlight_expansion=&#8221;default&#8221; underline_thickness=&#8221;2px&#8221; text_direction=&#8221;default&#8221;]\n<h5 style=\"text-align: center;\"><a href=\"#presse\"><em>Presses<\/em><\/a> et <a href=\"#presapezzo\"><em>grip piece<\/em><\/a> sit aliquam <a href=\"#macchine\"><em>special machines<\/em><\/a> sed <a href=\"#lean\"><em>lean production<\/em><\/a> secum <strong>food<\/strong> and <a href=\"http:\/\/biomedicale\"><em>biomedical<\/em><\/a><\/h5>\n[\/nectar_highlighted_text][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_color=&#8221;rgba(242,242,242,0.6)&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;7%&#8221; bottom_padding=&#8221;6%&#8221; left_padding_desktop=&#8221;15%&#8221; constrain_group_2=&#8221;yes&#8221; right_padding_desktop=&#8221;15%&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; disable_element=&#8221;yes&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; left_padding_desktop=&#8221;4%&#8221; constrain_group_2=&#8221;yes&#8221; right_padding_desktop=&#8221;4%&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; centered_text=&#8221;true&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][vc_column_text text_direction=&#8221;default&#8221;]\n<h3 style=\"text-align: center;\"><strong><span style=\"color: #111b27;\">Biomedical<\/span><\/strong><\/h3>\n[\/vc_column_text][divider line_type=&#8221;No Line&#8221; custom_height=&#8221;20&#8243;][vc_column_text text_direction=&#8221;default&#8221;]\n<p style=\"text-align: center;\">I am text block. Click edit button to change this text. Lorem ipsum dolor sit amet, consectetur adipiscing elit. Ut elit tellus, luctus nec ullamcorper mattis, pulvinar dapibus leo. I am text block. Click edit button to change this text. Lorem ipsum dolor sit amet, consectetur adipiscing elit.<\/p>\n[\/vc_column_text][nectar_cta btn_style=&#8221;basic&#8221; heading_tag=&#8221;h1&#8243; button_color=&#8221;extra-color-1&#8243; button_color_hover=&#8221;#ff0099&#8243; text_color=&#8221;#ffffff&#8221; button_border_thickness=&#8221;0px&#8221; link_type=&#8221;new_tab&#8221; alignment=&#8221;center&#8221; alignment_tablet=&#8221;default&#8221; alignment_phone=&#8221;default&#8221; constrain_group_3=&#8221;yes&#8221; constrain_group_4=&#8221;yes&#8221; display=&#8221;block&#8221; display_tablet=&#8221;inherit&#8221; display_phone=&#8221;inherit&#8221; icon_family=&#8221;none&#8221; link_text=&#8221;CTA&#8221; padding_top=&#8221;14&#8243; padding_bottom=&#8221;14&#8243; padding_left=&#8221;35&#8243; padding_right=&#8221;35&#8243; url=&#8221;#&#8221; font_size_desktop=&#8221;20px&#8221; margin_top=&#8221;40px&#8221;][\/vc_column_inner][\/vc_row_inner][vc_gallery type=&#8221;flickity_style&#8221; flickity_spacing=&#8221;default&#8221; flickity_controls=&#8221;material_pagination&#8221; flickity_overflow=&#8221;visible&#8221; flickity_wrap_around=&#8221;wrap&#8221; flickity_desktop_columns=&#8221;1&#8243; flickity_small_desktop_columns=&#8221;1&#8243; flickity_tablet_columns=&#8221;1&#8243; flickity_phone_columns=&#8221;1&#8243; flickity_box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; onclick=&#8221;link_no&#8221; img_size=&#8221;full&#8221;][nectar_highlighted_text color_type=&#8221;regular&#8221; highlight_color=&#8221;#3300ff&#8221; text_color=&#8221;#111b27&#8243; style=&#8221;regular_underline&#8221; highlight_expansion=&#8221;default&#8221; underline_thickness=&#8221;2px&#8221; text_direction=&#8221;default&#8221;]\n<h5 style=\"text-align: center;\"><a href=\"#presse\"><em>Presses<\/em><\/a> et <a href=\"#presapezzo\"><em>grip piece<\/em><\/a> sit aliquam <a href=\"#macchine\"><em>special machines<\/em><\/a> sed <a href=\"#lean\"><em>lean production<\/em><\/a> secum <a href=\"#alimentare\"><em>food<\/em><\/a> and <strong>biomedical<\/strong><\/h5>\n[\/nectar_highlighted_text][\/vc_column][\/vc_row]\n","protected":false},"excerpt":{"rendered":"<p>[vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_color=&#8221;#111b27&#8243; bg_image=&#8221;50&#8243; bg_position=&#8221;center center&#8221; background_image_loading=&#8221;default&#8221; bg_repeat=&#8221;no-repeat&#8221; animated_gradient_bg=&#8221;true&#8221; animated_gradient_bg_color_1=&#8221;#3300ff&#8221; animated_gradient_bg_color_2=&#8221;#111b27&#8243; animated_gradient_bg_speed=&#8221;850&#8243; animated_gradient_bg_blending_mode=&#8221;linear&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;12%&#8221; constrain_group_1=&#8221;yes&#8221; bottom_padding=&#8221;12%&#8221; text_color=&#8221;light&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; color_overlay=&#8221;#111b27&#8243; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221;&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-1348","page","type-page","status-publish"],"_links":{"self":[{"href":"https:\/\/mcservice.mo.it\/en\/wp-json\/wp\/v2\/pages\/1348","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mcservice.mo.it\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/mcservice.mo.it\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/mcservice.mo.it\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/mcservice.mo.it\/en\/wp-json\/wp\/v2\/comments?post=1348"}],"version-history":[{"count":0,"href":"https:\/\/mcservice.mo.it\/en\/wp-json\/wp\/v2\/pages\/1348\/revisions"}],"wp:attachment":[{"href":"https:\/\/mcservice.mo.it\/en\/wp-json\/wp\/v2\/media?parent=1348"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}